{"id":10405,"date":"2015-04-23T09:00:25","date_gmt":"2015-04-23T12:00:25","guid":{"rendered":"http:\/\/patagoniambiental.com.ar\/?p=10405"},"modified":"2015-04-23T09:00:25","modified_gmt":"2015-04-23T12:00:25","slug":"lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/","title":{"rendered":"\u00abLo que qued\u00f3 es una nube de millones de toneladas de ceniza\u00bb, dijo el gobernador de Neuqu\u00e9n"},"content":{"rendered":"<p>San Mart\u00edn de los Andes.-Jorge Sapag, que se encuentra en San Mart\u00edn de Los Andes, declar\u00f3 que se repartieron barbijos y, adem\u00e1s, pidi\u00f3 calma.<!--more--><\/p>\n<p>La inesperada erupci\u00f3n del volc\u00e1n Calbuco, que llevaba inactivo 43 a\u00f1os, provoc\u00f3 el Alerta Roja en Chile y la pronta acci\u00f3n preventiva en la provincia argentina de Neuqu\u00e9n por la proximidad a la zona afectada<\/p>\n<p>El gobernador Jorge Sapag confirm\u00f3 que se cerraron varios aeropuertos de la provincia y que se repartieron barbijos.<\/p>\n<p>\u00abSe han suspendido las clases, se est\u00e1n repartiendo barbijos y le quiero decir a la gente que se qued\u00e9 en su casa. Lo m\u00e1s importante es mantener la calma, Defensa Civil y la polic\u00eda est\u00e1n a cargo del plan de contingencia. Pero si la gente quiere salir a la calle, le recomendamos que lo hagan con barbijos y lentes\u00bb, expres\u00f3 el gobernador.<\/p>\n<p>Por \u00faltimo agreg\u00f3 que: \u00abNuestros laboratorios de ambiente est\u00e1n analizando la ceniza, que es una m\u00e1s fina de la que esper\u00e1bamos. Lo que qued\u00f3 es una nube de millones de toneladas y por lo tanto se debe prestar atenci\u00f3n si lo vientos cambian los rumbos\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: Diario Veloz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Mart\u00edn de los Andes.-Jorge Sapag, que se encuentra en San Mart\u00edn de Los Andes, declar\u00f3 que se repartieron barbijos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10407,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[53],"tags":[],"class_list":["post-10405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;Lo que qued\u00f3 es una nube de millones de toneladas de ceniza&quot;, dijo el gobernador de Neuqu\u00e9n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Lo que qued\u00f3 es una nube de millones de toneladas de ceniza&quot;, dijo el gobernador de Neuqu\u00e9n\" \/>\n<meta property=\"og:description\" content=\"San Mart\u00edn de los Andes.-Jorge Sapag, que se encuentra en San Mart\u00edn de Los Andes, declar\u00f3 que se repartieron barbijos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-23T12:00:25+00:00\" \/>\n<meta name=\"author\" content=\"Patagonia Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\\\/\"},\"author\":{\"name\":\"Patagonia Ambiental\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\"},\"headline\":\"\u00abLo que qued\u00f3 es una nube de millones de toneladas de ceniza\u00bb, dijo el gobernador de Neuqu\u00e9n\",\"datePublished\":\"2015-04-23T12:00:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\\\/\"},\"wordCount\":222,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"General\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\\\/\",\"name\":\"\\\"Lo que qued\u00f3 es una nube de millones de toneladas de ceniza\\\", dijo el gobernador de Neuqu\u00e9n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-04-23T12:00:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abLo que qued\u00f3 es una nube de millones de toneladas de ceniza\u00bb, dijo el gobernador de Neuqu\u00e9n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\",\"name\":\"Patagonia Ambiental\",\"description\":\"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\",\"https:\\\/\\\/www.facebook.com\\\/share\\\/1C1V8Gv9BX\\\/?mibextid=qi2Omg\",\"@patagoniambiental\",\"https:\\\/\\\/youtube.com\\\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Lo que qued\u00f3 es una nube de millones de toneladas de ceniza\", dijo el gobernador de Neuqu\u00e9n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/","og_locale":"es_ES","og_type":"article","og_title":"\"Lo que qued\u00f3 es una nube de millones de toneladas de ceniza\", dijo el gobernador de Neuqu\u00e9n","og_description":"San Mart\u00edn de los Andes.-Jorge Sapag, que se encuentra en San Mart\u00edn de Los Andes, declar\u00f3 que se repartieron barbijos [&hellip;]","og_url":"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_author":"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","article_published_time":"2015-04-23T12:00:25+00:00","author":"Patagonia Ambiental","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/"},"author":{"name":"Patagonia Ambiental","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d"},"headline":"\u00abLo que qued\u00f3 es una nube de millones de toneladas de ceniza\u00bb, dijo el gobernador de Neuqu\u00e9n","datePublished":"2015-04-23T12:00:25+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/"},"wordCount":222,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/#primaryimage"},"thumbnailUrl":"","articleSection":["General"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/","url":"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/","name":"\"Lo que qued\u00f3 es una nube de millones de toneladas de ceniza\", dijo el gobernador de Neuqu\u00e9n","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-04-23T12:00:25+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/lo-que-quedo-es-una-nube-de-millones-de-toneladas-de-ceniza-dijo-el-gobernador-de-neuquen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"\u00abLo que qued\u00f3 es una nube de millones de toneladas de ceniza\u00bb, dijo el gobernador de Neuqu\u00e9n"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d","name":"Patagonia Ambiental","description":"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.","sameAs":["http:\/\/www.patagoniambiental.com.ar","https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","@patagoniambiental","https:\/\/youtube.com\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/10405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=10405"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/10405\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=10405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=10405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=10405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}