{"id":11508,"date":"2015-05-27T19:00:12","date_gmt":"2015-05-27T22:00:12","guid":{"rendered":"http:\/\/patagoniambiental.com.ar\/?p=11508"},"modified":"2015-05-27T19:00:12","modified_gmt":"2015-05-27T22:00:12","slug":"para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/","title":{"rendered":"PARA CONFORMAR EL MAPA E\u00d3LICO DE TIERRA DEL FUEGO: La UNTDF promueve la investigaci\u00f3n sobre energ\u00edas renovables no convencionales"},"content":{"rendered":"<p>Tierra del Fuego.-La Universidad de Tierra del Fuego inici\u00f3 importantes proyectos en materia de investigaci\u00f3n sobre energ\u00eda e\u00f3lica, a trav\u00e9s del Instituto de Desarrollo Econ\u00f3mico e Innovaci\u00f3n.<!--more--> La iniciativa busca establecer el progreso en la gesti\u00f3n de recursos para el desarrollo sostenible de la Provincia.<\/p>\n<p>Un equipo de docentes investigadores de la Universidad Nacional de Tierra del Fuego se encuentra, en este per\u00edodo, desarrollando diferentes l\u00edneas de investigaci\u00f3n en el \u00e1rea de energ\u00edas renovables obteniendo, hasta el momento, importantes avances en materia de energ\u00eda e\u00f3lica.<br \/>\nLa iniciativa toma real importancia ante las posibilidades de progreso que podr\u00edan ofrecer a Tierra del Fuego las energ\u00edas renovables no convencionales y la gesti\u00f3n integral de estos recursos para el desarrollo sostenible de la Provincia. De estas acciones pr\u00f3ximamente se conformar\u00e1 el mapa e\u00f3lico de Tierra del Fuego.<br \/>\nEl Mg.Ing.Aeron Pablo Lerzo, docente investigador de la UNTDF y coordinador general de los proyectos destac\u00f3 que \u201cla Universidad a trav\u00e9s del Instituto de Desarrollo Econ\u00f3mico e Innovaci\u00f3n (IDEI) est\u00e1 profundamente involucrada en un \u00e1rea cr\u00edtica como es la energ\u00eda renovable y, para ello, tenemos dos importantes proyectos de envergadura que se encuentran en etapa incipiente, pero con importantes avances en materia de energ\u00eda e\u00f3lica\u201d, sostuvo.<br \/>\nEntre los proyectos m\u00e1s ambiciosos el especialista coment\u00f3 que se encuentra la instalaci\u00f3n en R\u00edo Grande de dos turbinas de 2.5 MW y cinco microturbinas de 4,5 KW en sectores aislados sin interconexi\u00f3n, con el fin de promover en esa ciudad la diversificaci\u00f3n de la matriz energ\u00e9tica. Es en el marco, de una propuesta presentada ante el Ministerio de Ciencia y Tecnolog\u00eda de Innovaci\u00f3n Productiva de la Naci\u00f3n (MINCYT) en una acci\u00f3n conjunta con la Cooperativa El\u00e9ctrica riograndense.<br \/>\nDe este modo, el objetivo general del proyecto es investigar y experimentar la viabilidad de producci\u00f3n de energ\u00eda e\u00f3lica en la Tierra del Fuego, (desde la selecci\u00f3n de equipos, puesta en marcha e instalaci\u00f3n, hasta la operaci\u00f3n de producci\u00f3n, los problemas particulares geogr\u00e1ficos, ambientales y climatol\u00f3gicos, el mantenimiento y la relaci\u00f3n costo\u2013beneficio de turbinas e\u00f3licas de diferente potencia) para generar informaci\u00f3n, conocimientos innovadores y estudios aplicados.<br \/>\nEl equipo multidisciplinario de investigadores que se encuentra a cargo de este proyecto, est\u00e1 integrado adem\u00e1s por el economista Francisco Gatto, los f\u00edsicos Marcos y Lucas Valluzzi, quienes trabajan en su doctorado de la Universidad de La Plata con el desarrollo de materiales nanoestructurados para la creaci\u00f3n de placas fotovoltaicas tipo \u201cThin Film\u201d y \u201cMultiLayer\u201d para la generaci\u00f3n eficiente de energ\u00eda fotovoltaica. Este grupo de cient\u00edficos se encuentra abocado tambi\u00e9n al estudio de los fen\u00f3menos de engelamiento, en rotores de palas e\u00f3licas que ocurre en las condiciones naturales del climas fr\u00edo extremo; para lo cual se realizan ensayos exhaustivos en Ushuaia.<br \/>\nPor \u00faltimo, Pablo Lerzo, destac\u00f3 el potencial que tiene la provincia en relaci\u00f3n a la posibilidad de consolidar un desarrollo energ\u00e9tico con energ\u00edas limpias. \u201cEl factor de capacidad es muy importante para la Patagonia y Tierra del Fuego, que cuenta con vientos de excelente calidad \u00fanicos en el mundo y que en la Patagonia chilena ya son explotados\u201d, sostuvo. \u201cEn nuestro pa\u00eds el desarrollo de estos recursos es muy incipiente \u2013enfatiz\u00f3 el ingeniero\u2013 y desde el IDEI estamos \u201chaciendo punta\u201d poniendo en valor este recurso que es important\u00edsimo y que deber\u00edamos ponerlo a funcionar cuanto antes, para cambiar la matriz energ\u00e9tica y promover un desarrollo sustentable como lo hacen los pa\u00edses del primer mundo\u201d.<br \/>\nCabe destacar que en materia de energ\u00edas renovables, para la Universidad Nacional de Tierra del Fuego, estas l\u00edneas de investigaci\u00f3n son solo el principio de una gran cantidad objetivos institucionales que buscan acompa\u00f1ar el desarrollo social y econ\u00f3mico del territorio. En ese sentido, se proyecta trabajar en las \u00e1reas de energ\u00edas micro hidr\u00e1ulica, mareomotriz, undimotriz (energ\u00eda de las olas) y corrientes marinas en el Canal de Beagle.<br \/>\n<strong>La UNTDF, en l\u00ednea con las \u00faltimas tendencias en investigaci\u00f3n<\/strong><\/p>\n<p>El ingeniero aeron\u00e1utico Pablo Lerzo particip\u00f3 en el mes de abril de una serie de encuentros en el parque cient\u00edfico de la Universidad de Salamanca, Espa\u00f1a; oportunidad en la que accedi\u00f3 a una capacitaci\u00f3n sobre herramientas SARP, lo que actualmente se conoce como \u201cdrones\u201d. Se trata de los nuevos sistemas a\u00e9reos remotamente pilotados, con c\u00e1maras y sensores de tipo visuales que son utilizados para relevar datos de las turbinas productoras de energ\u00eda e\u00f3licas.<br \/>\nA ra\u00edz de esta experiencia in\u00e9dita Lerzo fue convocado a participar del \u201cCongreso viento y energ\u00eda\u201d desarrollado posteriormente en Buenos Aires, por el Consejo Profesional de Ingenier\u00eda mec\u00e1nica. En ese marco, disert\u00f3 en nombre de la UNTDF y present\u00f3 esta tecnolog\u00eda a los operadores de los parques e\u00f3licos m\u00e1s grande del pa\u00eds, oportunidad en la que se analizaron los potenciales que ofrecen estas herramientas tecnol\u00f3gicas, al servicio del desarrollo productivo.<br \/>\nFuente: El Diario del Fin del Mundo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tierra del Fuego.-La Universidad de Tierra del Fuego inici\u00f3 importantes proyectos en materia de investigaci\u00f3n sobre energ\u00eda e\u00f3lica, a trav\u00e9s [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2416,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[53],"tags":[314,454],"class_list":["post-11508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-energias-renovables","tag-untdf"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>PARA CONFORMAR EL MAPA E\u00d3LICO DE TIERRA DEL FUEGO: La UNTDF promueve la investigaci\u00f3n sobre energ\u00edas renovables no convencionales<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PARA CONFORMAR EL MAPA E\u00d3LICO DE TIERRA DEL FUEGO: La UNTDF promueve la investigaci\u00f3n sobre energ\u00edas renovables no convencionales\" \/>\n<meta property=\"og:description\" content=\"Tierra del Fuego.-La Universidad de Tierra del Fuego inici\u00f3 importantes proyectos en materia de investigaci\u00f3n sobre energ\u00eda e\u00f3lica, a trav\u00e9s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-27T22:00:12+00:00\" \/>\n<meta name=\"author\" content=\"Patagonia Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\\\/\"},\"author\":{\"name\":\"Patagonia Ambiental\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\"},\"headline\":\"PARA CONFORMAR EL MAPA E\u00d3LICO DE TIERRA DEL FUEGO: La UNTDF promueve la investigaci\u00f3n sobre energ\u00edas renovables no convencionales\",\"datePublished\":\"2015-05-27T22:00:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\\\/\"},\"wordCount\":904,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"energias renovables\",\"UNTDF\"],\"articleSection\":[\"General\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\\\/\",\"name\":\"PARA CONFORMAR EL MAPA E\u00d3LICO DE TIERRA DEL FUEGO: La UNTDF promueve la investigaci\u00f3n sobre energ\u00edas renovables no convencionales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-05-27T22:00:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PARA CONFORMAR EL MAPA E\u00d3LICO DE TIERRA DEL FUEGO: La UNTDF promueve la investigaci\u00f3n sobre energ\u00edas renovables no convencionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\",\"name\":\"Patagonia Ambiental\",\"description\":\"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\",\"https:\\\/\\\/www.facebook.com\\\/share\\\/1C1V8Gv9BX\\\/?mibextid=qi2Omg\",\"@patagoniambiental\",\"https:\\\/\\\/youtube.com\\\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PARA CONFORMAR EL MAPA E\u00d3LICO DE TIERRA DEL FUEGO: La UNTDF promueve la investigaci\u00f3n sobre energ\u00edas renovables no convencionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/","og_locale":"es_ES","og_type":"article","og_title":"PARA CONFORMAR EL MAPA E\u00d3LICO DE TIERRA DEL FUEGO: La UNTDF promueve la investigaci\u00f3n sobre energ\u00edas renovables no convencionales","og_description":"Tierra del Fuego.-La Universidad de Tierra del Fuego inici\u00f3 importantes proyectos en materia de investigaci\u00f3n sobre energ\u00eda e\u00f3lica, a trav\u00e9s [&hellip;]","og_url":"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_author":"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","article_published_time":"2015-05-27T22:00:12+00:00","author":"Patagonia Ambiental","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/"},"author":{"name":"Patagonia Ambiental","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d"},"headline":"PARA CONFORMAR EL MAPA E\u00d3LICO DE TIERRA DEL FUEGO: La UNTDF promueve la investigaci\u00f3n sobre energ\u00edas renovables no convencionales","datePublished":"2015-05-27T22:00:12+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/"},"wordCount":904,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/#primaryimage"},"thumbnailUrl":"","keywords":["energias renovables","UNTDF"],"articleSection":["General"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/","url":"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/","name":"PARA CONFORMAR EL MAPA E\u00d3LICO DE TIERRA DEL FUEGO: La UNTDF promueve la investigaci\u00f3n sobre energ\u00edas renovables no convencionales","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-05-27T22:00:12+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/para-conformar-el-mapa-eolico-de-tierra-del-fuego-la-untdf-promueve-la-investigacion-sobre-energias-renovables-no-convencionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"PARA CONFORMAR EL MAPA E\u00d3LICO DE TIERRA DEL FUEGO: La UNTDF promueve la investigaci\u00f3n sobre energ\u00edas renovables no convencionales"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d","name":"Patagonia Ambiental","description":"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.","sameAs":["http:\/\/www.patagoniambiental.com.ar","https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","@patagoniambiental","https:\/\/youtube.com\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/11508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=11508"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/11508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=11508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=11508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=11508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}