{"id":2017,"date":"2008-09-27T15:35:49","date_gmt":"2008-09-27T18:35:49","guid":{"rendered":"http:\/\/patagoniambiental.com.ar\/?p=2017"},"modified":"2008-09-27T15:35:49","modified_gmt":"2008-09-27T18:35:49","slug":"conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/","title":{"rendered":"Conclusiones de la Asamblea por la Sanidad de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro, Ciudad de Plottier,  27\/09\/08, Neuqu\u00e9n."},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Asamblea por la Sanidad de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro.-<\/strong>En Plottier, en las instalaciones del CPEM N\u00ba 55, siendo las 16,30 horas del d\u00eda 27 de setiembre de 2.008, se re\u00fane la \u00abAsamblea por la sanidad de los r\u00edos\u00bb de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro.<!--more--><br \/>\nAdem\u00e1s de la organizaci\u00f3n anfitriona, la Asociaci\u00f3n Ambientalista Rinc\u00f3n Limay de Plottier, participaron diversas organizaciones como U\u00f1opatun y la Asamblea por la sanidad de los R\u00edos de Viedma y Patagones,\u00a0 el Foro Ciudadano de Neuqu\u00e9n, la CTA R\u00edo Negro, la Fundaci\u00f3n Ecosur, la coordinadora de la Comisi\u00f3n de Medio Ambiente del B\u00ba R\u00edo Grande de Neuqu\u00e9n Capital, la agrupaci\u00f3n de vecinos contra la contaminaci\u00f3n de la planta de tratamiento cloacales de calle Tronador de Neuqu\u00e9n Capital, la radio FM la Roca de Plottier, Comisi\u00f3n Vecinal del B\u00ba Rinc\u00f3n de Emilio de Neuqu\u00e9n, el Grupo Moreno, Aten Plottier, Agrupaci\u00f3n 4 de abril de la UNTER Cipolletti, la Junta Interna de ATE del Ente Provincial de Agua y Saneamiento de Neuqu\u00e9n, la CTA Neuqu\u00e9n, la Confederaci\u00f3n de Organizaciones Mapuches, una delegada de la Cooperativa de Agua de Plottier, ASSUPA, la Fundaci\u00f3n Aguas Patag\u00f3nicas, el grupo Todos por la Tierra de Cipolletti, la Asociaci\u00f3n Civil de Ecolog\u00eda Asamblea Coordinadora Patag\u00f3nica contra el Saqueo y la Contaminaci\u00f3n, y a la Red Nacional de Acci\u00f3n Ecologista RENACE, la Sociedad de Pediatr\u00eda de R\u00edo Negro y Neuqu\u00e9n, Defensa Civil de Neuqu\u00e9n y productores frutihort\u00edcolas locales, trabajadores de la educaci\u00f3n, vecinos de Roca, Jun\u00edn de los Andes, Plottier, Neuqu\u00e9n Capital y Cipolletti,<br \/>\nLa Dra. Griselda Mattio, de la Asociaci\u00f3n Ambientalista Rinc\u00f3n Limay, hace la apertura de la asamblea y presenta el desarrollo de la misma. Luego Elvio Mendioroz de U\u00f1opatun y la Asamblea por la Sanidad de los R\u00edos hace un panorama del surgimiento de dicha Asamblea, explicando el concepto de cuenca \u00fanica desde el lago Nahuel Huapi hasta la desembocadura del R\u00edo Negro y una peque\u00f1a rese\u00f1a de las acciones llevadas a cabo desde los inicios.<br \/>\nA continuaci\u00f3n se pasa a deliberar y exponer sobre el particular y sobre los puntos de contaminaci\u00f3n que van a ir prefigurando el Mapa de la Verdad, donde quedar\u00e1n registrados los puntos y factores que atentan contra la sanidad a lo largo de toda la Cuenca.<br \/>\nSe realizan aportes acerca de la contaminaci\u00f3n del llamado Canal de los Milicos en Cipolletti, del arroyo Dur\u00e1n en Neuqu\u00e9n Capital, del r\u00edo Chimehu\u00edn en Jun\u00edn de los Andes. Tambi\u00e9n se denuncia la falta de control de focos contaminantes en plantas industriales como el caso de Capex o la industria petrolera (uso de trazadores radiactivos).<br \/>\nComo parte de la sanidad de los r\u00edos, se expone sobre el apropiamiento de las riberas de r\u00edos y lagos en un proceso de especulaci\u00f3n inmobiliaria, y se detalla el caso del establecimiento de Los Canales de Plottier, otros casos que incluye el asesinato del vecino Cristian Mu\u00f1oz, el caso de Ted Turner en Villa Traful.<br \/>\nOtros casos paradigm\u00e1ticos que se denunciaron fueron los de las presas sobre el R\u00edo Neuqu\u00e9n y el dique\u00a0 Portezuelo Grande y el da\u00f1o sobre la superficie de campos que ocasiona la industria petroleras con picadas, ductos, etc..<br \/>\nEn todos estos casos, as\u00ed como en los casos de contaminaci\u00f3n, se pone en evidencia la complicidad con las empresas de diversos organismos \u00e9 instituciones estatales como los Concejos Deliberantes, Parques Nacionales, la Orsep, AIC, gobiernos, etc. y la descoordinaci\u00f3n interesada entre los organismos que deben velar por la sanidad de lagos y r\u00edos.<br \/>\nVarios oradores proponen que esta Asamblea vote resoluciones pr\u00e1cticas que no queden s\u00f3lo en la denuncia. A tal efecto se anuncian algunas acciones como el festival que se organiza en Viedma, el acampe y acto en Villa Traful de los d\u00edas 21, 22 y 23 de noviembre. Tambi\u00e9n se proponen nuevas actividades como un abrazo a los r\u00edos en varias localidades en un d\u00eda a determinar y nuevas asambleas.<br \/>\nDe com\u00fan acuerdo se resuelve:<br \/>\n1) Prepara un documento \u00fanico.<br \/>\n2) Realizar el \u00abMapa de la Verdad\u00bb con todos los puntos de contaminaci\u00f3n a lo largo de la Cuenca.<br \/>\n3) Participar del festival art\u00edstico del 18 de octubre en la Escuela N\u00ba 2 de Viedma.<br \/>\n4) Participar del acampe y acto en Villa Traful, frente a la estancia de Ted Turner, los d\u00edas 21, 22 y 23 de noviembre, como acci\u00f3n reivindicadora de la soberan\u00eda nacional y por la expropiaci\u00f3n de los terrenos necesarios para el libre acceso a los caminos de sirga y riberas.<br \/>\n5) Convocar una vez elaborado el documento a una conferencia de prensa conjunta de todas las organizaciones.<br \/>\n6) Aportar a las reuniones que se realizan los primeros s\u00e1bados de cada mes en la revista 8.300 con materiales y presencia.<br \/>\n7) Conformar la Uni\u00f3n de Asambleas por la Sanidad de la Cuenca del Nahuel Huapi, Limay, Neuqu\u00e9n y Negro, con asambleas en todas las localidades.<br \/>\n8) Convocar a una nueva Asamblea General el 8 de noviembre en Viedma.<br \/>\n9) Convocar a una Asamblea Regional de Neuqu\u00e9n y el Alto Valle del R\u00edo Negro en Cipolletti en fecha a determinar.<br \/>\n10)\u00a0 Tener presente el planteo cultural, pol\u00edtico, legislativo y judicial en todos los lugares que se debata la recomposici\u00f3n y preservaci\u00f3n ambiental\u00a0 de la cuenca del lago Nahuel Huapi, r\u00edos Limay, Neuqu\u00e9n y R\u00edo Negro,<br \/>\nUNION DE ASAMBLEAS DE CIUDADANOS AUTOCONVOCADOS POR LA SANIDAD DE LA CUENCA DEL LAGO NAHUEL HUAPI Y LOS R\u00cdOS LIMAY, NEUQU\u00c9N Y NEGRO<br \/>\nJ.J. Biedma 87 \u2013 CP 8504 &#8211; Carmen de Patagones \u2013 02920 464.222 \/ 424.269 unopatun@rnonline.com.ar\u00a0\u00a0 www.eco-comarca.com.ar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asamblea por la Sanidad de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro.-En Plottier, en las instalaciones del CPEM N\u00ba [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2018,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1,3],"tags":[80,81,78,82],"class_list":["post-2017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-ong","tag-asamblea","tag-cta","tag-cuenca","tag-unter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conclusiones de la Asamblea por la Sanidad de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro, Ciudad de Plottier, 27\/09\/08, Neuqu\u00e9n.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conclusiones de la Asamblea por la Sanidad de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro, Ciudad de Plottier, 27\/09\/08, Neuqu\u00e9n.\" \/>\n<meta property=\"og:description\" content=\"Asamblea por la Sanidad de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro.-En Plottier, en las instalaciones del CPEM N\u00ba [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg\" \/>\n<meta property=\"article:published_time\" content=\"2008-09-27T18:35:49+00:00\" \/>\n<meta name=\"author\" content=\"Patagonia Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\\\/\"},\"author\":{\"name\":\"Patagonia Ambiental\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\"},\"headline\":\"Conclusiones de la Asamblea por la Sanidad de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro, Ciudad de Plottier, 27\\\/09\\\/08, Neuqu\u00e9n.\",\"datePublished\":\"2008-09-27T18:35:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\\\/\"},\"wordCount\":1008,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Asamblea\",\"CTA\",\"Cuenca\",\"UNTER\"],\"articleSection\":[\"Noticias\",\"ONG\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\\\/\",\"name\":\"Conclusiones de la Asamblea por la Sanidad de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro, Ciudad de Plottier, 27\\\/09\\\/08, Neuqu\u00e9n.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2008-09-27T18:35:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conclusiones de la Asamblea por la Sanidad de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro, Ciudad de Plottier, 27\\\/09\\\/08, Neuqu\u00e9n.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\",\"name\":\"Patagonia Ambiental\",\"description\":\"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\",\"https:\\\/\\\/www.facebook.com\\\/share\\\/1C1V8Gv9BX\\\/?mibextid=qi2Omg\",\"@patagoniambiental\",\"https:\\\/\\\/youtube.com\\\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conclusiones de la Asamblea por la Sanidad de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro, Ciudad de Plottier, 27\/09\/08, Neuqu\u00e9n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/","og_locale":"es_ES","og_type":"article","og_title":"Conclusiones de la Asamblea por la Sanidad de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro, Ciudad de Plottier, 27\/09\/08, Neuqu\u00e9n.","og_description":"Asamblea por la Sanidad de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro.-En Plottier, en las instalaciones del CPEM N\u00ba [&hellip;]","og_url":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_author":"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","article_published_time":"2008-09-27T18:35:49+00:00","author":"Patagonia Ambiental","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/"},"author":{"name":"Patagonia Ambiental","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d"},"headline":"Conclusiones de la Asamblea por la Sanidad de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro, Ciudad de Plottier, 27\/09\/08, Neuqu\u00e9n.","datePublished":"2008-09-27T18:35:49+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/"},"wordCount":1008,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/#primaryimage"},"thumbnailUrl":"","keywords":["Asamblea","CTA","Cuenca","UNTER"],"articleSection":["Noticias","ONG"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/","url":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/","name":"Conclusiones de la Asamblea por la Sanidad de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro, Ciudad de Plottier, 27\/09\/08, Neuqu\u00e9n.","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/#primaryimage"},"thumbnailUrl":"","datePublished":"2008-09-27T18:35:49+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-la-asamblea-por-la-sanidad-de-la-cuenca-nahuel-huapi-limay-neuquen-y-negro-ciudad-de-plottier-270908-neuquen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"Conclusiones de la Asamblea por la Sanidad de la Cuenca Nahuel Huapi, Limay, Neuqu\u00e9n y Negro, Ciudad de Plottier, 27\/09\/08, Neuqu\u00e9n."}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d","name":"Patagonia Ambiental","description":"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.","sameAs":["http:\/\/www.patagoniambiental.com.ar","https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","@patagoniambiental","https:\/\/youtube.com\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/2017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=2017"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/2017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=2017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=2017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=2017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}