{"id":2072,"date":"2008-05-17T14:15:10","date_gmt":"2008-05-17T17:15:10","guid":{"rendered":"http:\/\/patagoniambiental.com.ar\/?p=2072"},"modified":"2008-05-17T14:15:10","modified_gmt":"2008-05-17T17:15:10","slug":"conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/","title":{"rendered":"Conclusiones de los temas tratados en la Asamblea de Ciudadanos Autoconvocados por la Sanidad de los R\u00edos Limay, Neuqu\u00e9n y Negro"},"content":{"rendered":"<p style=\"text-align: justify;\">Viedma (Asamblea de Ciudadanos Autoconvocados por la Sanidad de los r\u00edos Limay, Neuqu\u00e9n y Negro).\u00a0El d\u00eda 17 de mayo se llevo a cabo la ASAMBLEA DE CIUDADANOS AUTOCONVOCADOS POR LA SANIDAD DE LOS R\u00cdOS LIMAY, NEUQU\u00c9N Y NEGRO,<!--more--> en el Centro Escuela Media (CEM 4) de Viedma. A continuaci\u00f3n se detallan los antecedentes de como naci\u00f3 la Asamblea y las conclusiones a las que se arribo en el encuentro.<\/p>\n<p style=\"text-align: justify;\">Antecedentes:<br \/>\nLa Asamblea se inici\u00f3 relatando la primera denuncia relacionada con la contaminaci\u00f3n cloacal, industrial y agroqu\u00edmica de los r\u00edos Limay, Neuqu\u00e9n y Negro, formulada ya en el\u00a0 a\u00f1o 1962 por los ciudadanos viedmenses N\u00e9stor G\u00f3mez, Oscar Sanguinetti y Alberto \u201cTiclo\u201d L\u00f3pez, quienes navegaron el r\u00edo desde la ciudad de Neuqu\u00e9n hasta Viedma enarbolando la\u00a0 pancarta \u201cAuxilio, el r\u00edo se ahoga\u201d. Luego se ley\u00f3 la Ley N\u00ba 2.797 de Protecci\u00f3n de las Aguas de la Naci\u00f3n Argentina promulgada en \u00bf18XX?: \u201clas aguas cloacales y los residuos industriales no podr\u00e1n ser arrojados a los r\u00edos de la Rep\u00fablica si no han sido sometidos previamente a un tratamiento de purificaci\u00f3n\u201d. Se analiz\u00f3 el tiempo desde el cual ya se infringe la Ley en menosprecio de la calidad sanitaria de los r\u00edos. Luego, se ley\u00f3 el Art. 41 de la Constituci\u00f3n Nacional al respecto del derecho y deber de los ciudadanos argentinos de resguardar nuestros bienes naturales, haciendo especial hincapi\u00e9 en el alcance del p\u00e1rrafo que afirma: \u201cEl da\u00f1o ambiental generar\u00e1 prioritariamente la obligaci\u00f3n de recomponer, seg\u00fan lo establezca la ley\u201d.<\/p>\n<p style=\"text-align: justify;\">A continuaci\u00f3n se inform\u00f3 sobre la carta presentada por esta Asamblea al Gobernador de la Provincia de R\u00edo Negro, Miguel Saiz, y al Gobernador de la Provincia de Buenos Aires, Daniel Scioli, manifest\u00e1ndoles nuestra objeci\u00f3n a la\u00a0 firma del acuerdo para la disposici\u00f3n de Fondos P\u00fablicos para el \u201cProyecto de Riego: \u201cConesa\u2013Guardia Mitre\u2013Patagones\u201d, hasta tanto no hayan recompuesto cada uno de los focos contaminantes de origen cloacal, industrial y agroqu\u00edmico que, al ser volcados al agua del r\u00edo \u2013sin tratamiento de purificaci\u00f3n, ni control de uso\u2013 contaminan la cuenca de nuestros r\u00edos Limay, Neuqu\u00e9n y Negro, y por ende perjudican nuestra salud.<\/p>\n<p style=\"text-align: justify;\">Responsables:<br \/>\nActo seguido, y sobre la base de los preceptos del Art. 41, se cuestion\u00f3 acerca de saber qui\u00e9n fue el funcionario de Gobierno responsable de haber destinado fondos p\u00fablicos para la realizaci\u00f3n de la costanera de Viedma, cuando en el mismo periodo de tiempo reconoc\u00edan que la planta de tratamiento de residuos cloacales de esta ciudad funcionaba a medias, que estaba por colapsar, y que finalmente dej\u00f3 de operar en diciembre de 2007, para volcar el crudo de sus cloacas al r\u00edo hasta la actualidad.<br \/>\nTal peso de responsabilidad recay\u00f3 primero en la figura del Intendente de Viedma, Jorge Ferreira, quien como responsable pol\u00edtico de la comunidad hab\u00eda solicitado a la Autoridad Interjurisdiccional de la Cuenca de los R\u00edo Limay, Neuqu\u00e9n y Negro \u2013AIC\u2013 la disposici\u00f3n de fondos para la Costanera de Viedma, a conciencia de que la planta de tratamiento de las cloacas de su ciudad no funcionaba correctamente, sin considerar primero la potencial contaminaci\u00f3n y el perjuicio que tal desperfecto provocar\u00eda en la salud de las poblaciones de Viedma y Carmen de Patagones, sin reconocer ni respetar los principios de Pol\u00edtica Ecol\u00f3gica establecidos en los art\u00edculos 84 y 85 de la Constituci\u00f3n de la Provincia de R\u00edo Negro, ni el Art. 41 de la Constituci\u00f3n Nacional.<br \/>\nLuego fue se\u00f1alado Horacio Collado, quien como responsable del Departamento Provincial de Aguas de la Provincia de R\u00edo Negro, ten\u00eda perfecto conocimiento acerca del\u00a0 incorrecto y \/ o nulo funcionamiento de la planta citada,\u00a0 y a pesar de eso\u00a0 consinti\u00f3 el destino de fondos del erario p\u00fablico para la construcci\u00f3n de la costanera, en vez de recomponer primero su planta de tratamiento de residuos cloacales, incumpliendo as\u00ed la Ley 2.391 que otorga al DPA la autoridad de aplicaci\u00f3n en el control de calidad y protecci\u00f3n de los recursos h\u00eddricos provinciales que son utilizados como cuerpos receptores de residuos y afluentes, productos de la actividad del hombre; y tambi\u00e9n ignor\u00f3 la Ley 2952 \u2013C\u00f3digo de Aguas\u2013 en lo referido a la preservaci\u00f3n contra los efectos nocivos que pudieran afectar la calidad del agua del r\u00edo Negro.<br \/>\nDentro del marco de la reglamentaci\u00f3n provincial para la preservaci\u00f3n ambiental de la Provincia de R\u00edo Negro, se pretendi\u00f3 se\u00f1alar como responsable de la situaci\u00f3n planteada a Oscar Echeverr\u00eda, quien como Presidente del Consejo de Ecolog\u00eda y Medio Ambiente \u2013CODEMA\u2013 deber\u00eda haber cuestionado el incorrecto destino de los fondos, usados para la costanera\u00a0 en lugar de la planta de tratamiento de residuos cloacales. Dicho planteo qued\u00f3 de inmediato desestimado dada la probada corrupci\u00f3n ambiental de este funcionario, quien en reiteradas oportunidades ha demostrado que se debe primero a los indicativos pol\u00edticos de sus superiores, que a preservar los bienes naturales de la Provincia de R\u00edo Negro. Sobre este marco del cuestionable accionar del Departamento Provincial de Aguas \u2013DPA\u2013 y del CODEMA, tambi\u00e9n se se\u00f1al\u00f3 al Gobernador Miguel Saiz, por ser responsable directo de ambos organismos.<br \/>\nA continuaci\u00f3n se inform\u00f3 que el Concejo de Viedma hab\u00eda promulgado una Ordenanza a fin de confirmar la presencia del norovirus en el agua potable y \/ o en el agua de la ribera del r\u00edo Negro. (Cabe indicar que el norovirus fue se\u00f1alado como el principal agente que provoc\u00f3 el notable incremento de las patolog\u00edas gastrointestinales hasta hoy presentes en las comunidades de Viedma y Carmen de Patagones, tema tratado e informado a la sociedad en nuestra Asamblea del pasado 26 de abril<br \/>\nFinalmente, la responsabilidad por el incorrecto destino de los fondos usados para la costanera de Viedma, y no a la recomposici\u00f3n de su planta de tratamiento de efluentes cloacales, recay\u00f3 en la figura del Presidente de la Autoridad Interjurisdiccional de la Cuenca de los R\u00edos, Limay, Neuqu\u00e9n y Negro, Jorge Sapag, quien como responsable del control, uso, aprovechamiento y preservaci\u00f3n de la cuenca de estos r\u00edos, deber\u00eda haber tenido pleno conocimiento acerca del incorrecto funcionamiento de la planta en cuesti\u00f3n, ateni\u00e9ndose entonces a desestimar la solicitud del giro de fondos elevado por la Municipalidad de Viedma para la construcci\u00f3n de su costanera, hecho que efectivamente concret\u00f3, sin antes recomponer la planta, cuando: \u201cEl da\u00f1o ambiental generar\u00e1 prioritariamente la obligaci\u00f3n de recomponer, seg\u00fan lo establezca la ley\u201d. Art. 41 de la Constituci\u00f3n Argentina.<br \/>\nAl aludir a la AIC como organismo responsable por el incorrecto destino de los fondos p\u00fablicos, distintos asamble\u00edstas se\u00f1alaron que desde el inicio en el accionar de la AIC con las provincias y municipios ribere\u00f1os a los r\u00edos Limay, Neuqu\u00e9n y Negro, al menos en la provincia de R\u00edo Negro, la administraci\u00f3n de sus primeros fondos por regal\u00edas hidroenerg\u00e9ticas (U$A 20.000.000 de d\u00f3lares) fueron destinados por el entonces Gobernador Horacio Massachessi para el pago de sueldos de los empleados p\u00fablicos, y de all\u00ed en m\u00e1s, en cada una de la provincias y que con sus municipios la integran,\u00a0 los fondos de la AIC siempre tuvieron un destino pol\u00edtico-partidario, en lugar de destinarse con absoluta prioridad para la preservaci\u00f3n ambiental de los r\u00edos, y del resguardo ambiental sanitario del Lago Nahuel Huapi, obvio componente de la cuenca de los r\u00edos Limay y r\u00edo Negro.<br \/>\nLuego se se\u00f1al\u00f3 que ya los principios fundamentales que dieron origen a la constituci\u00f3n de la AIC en el a\u00f1o 1985, entienden que \u201ces necesario regular los recursos h\u00eddricos interprovinciales, dado que el concepto de cuencas trasciende los l\u00edmites pol\u00edticos establecidos\u201d, entendiendo que los costos para la edificaci\u00f3n de plantas de tratamiento de efluentes cloacales y \/ o industriales por lo com\u00fan exceden la recaudaci\u00f3n oficial o privada como para poder asumir su construcci\u00f3n, y que la recaudaci\u00f3n por regal\u00edas hidroenerg\u00e9ticas debe tener como principal fin contemplar primero la asistencia financiera para su consolidaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Reflexiones<br \/>\nCabe indicar que ya desde la conformaci\u00f3n de esta ASAMBLEA DE CIUDADANOS POR LA SANIDAD DE LOS R\u00cdOS LIMAY, NEUQUEN Y NEGRO en febrero de 2008, se se\u00f1al\u00f3 a la AIC como el principal organismo responsable por velar y actuar con absoluta prioridad en el resguardo ambiental del lago Nahuel Huapi y de la cuenca de los r\u00edos Limay, Neuqu\u00e9n y Negro, no solamente porque la\u00a0 Ley 23.896 del Senado y C\u00e1mara de Diputados de la Naci\u00f3n; la Ley 1.651, decreto 2.197 de la Provincia de Neuqu\u00e9n; la Ley 10.452 de la Provincia de Buenos Aires, y la Ley 2.088 de la Provincia de R\u00edo Negro le otorgan esta potestad, sino tambi\u00e9n porque es el \u00fanico organismo que por su conformaci\u00f3n interprovincial cuenta con los informes municipales y provinciales sobre el estado del agua del r\u00edo en cada localidad lacustre y \/ o ribere\u00f1a competentes de la AIC, y por ende puede y debe tener una visi\u00f3n global \u201cecosistem\u00e1tica\u201d del sentido de cuenca que en su conjunto conforman el lago Nahuel Huapi, el r\u00edo Limay, el r\u00edo Neuqu\u00e9n y el r\u00edo Negro, y tambi\u00e9n en ellos agregados sus propios informes sobre la transformaci\u00f3n f\u00edsica, qu\u00edmica y biol\u00f3gica provocada en el agua de los embalses de cada una de las represas hidroenerg\u00e9ticas de los r\u00edos Limay y Neuqu\u00e9n. Y, sobre la base de tal reconocimiento ambiental de la cuenca, obrar en consecuencia otorgando prioridad a la preservaci\u00f3n de su ecosistema.<br \/>\nUn intendente de cualquier ciudad lacustre y \/ o ribere\u00f1a al Limay, Neuqu\u00e9n y Negro, o bien un gobernador de las tres provincias que la abarcan, no tiene porqu\u00e9 saber que aguas arriba, o abajo, en otra jurisdicci\u00f3n provincial, se atenta contra la salubridad del lago o del r\u00edo, ya sea porque una ciudad vuelca sus cloacas sin tratamiento previo, o bien porque una serie de industrias no cuentan con su respectiva planta de tratamiento, o porque se utilizan\u00a0 una serie de venenos agroqu\u00edmicos sin control alguno que en su acci\u00f3n residual contaminan su biota.<br \/>\nTal es el caso \u2013por ejemplo\u2013 del Gobernador de la Provincia de Buenos Aires, quien no tiene porqu\u00e9 saber que la Ciudad de Neuqu\u00e9n vuelca en crudo sus efluentes cloacales al r\u00edo Limay, o bien saber que en el -Canal de los Milicos \u2013ejido municipal de Cipolletti\u2013, el nauseabundo olor a podrido que emanan sus aguas se\u00f1alan su evidente contaminaci\u00f3n. De conocer esta situaci\u00f3n, sin dudas el Gobernador Scioli no hubiese firmado con el Gobernador Saiz un proyecto para la construcci\u00f3n de un canal de riego aguas abajo en el r\u00edo Negro, ya que como funcionario se debe a los dictados del Art. 41 de la Constituci\u00f3n Nacional, el cual le indica que \u201cante el da\u00f1o ambiental es prioridad recomponer, seg\u00fan lo establezca la Ley\u201d.<br \/>\nEn cambio, la AIC s\u00ed sabe sobre cada uno de los focos de contaminaci\u00f3n cloacal, industrial, agroqu\u00edmica y a\u00fan ahora tambi\u00e9n petrolera que hoy contaminan y envenenan nuestros lagos y r\u00edos patag\u00f3nicos, y es sobre la base de tal reconocimiento que debe primero recomponer cada uno de los focos contaminantes deteniendo todo proyecto de desarrollo municipal o provincial que sirva el caudal h\u00eddrico de los lagos y r\u00edos, que no incluya la prioridad de recomponer.<\/p>\n<p style=\"text-align: justify;\">Sucede tambi\u00e9n que, seg\u00fan indica el Estatuto que rige a la AIC, para que este organismo intervenga en la recomposici\u00f3n de un foco contaminante, debe existir una denuncia previa formulada desde\u00a0 una provincia o municipalidad sobre la otra, a fin de detener uno u otro foco de poluci\u00f3n interprovincial que la perjudique, situaci\u00f3n que tal como fuera expuesta, no necesariamente una provincia o municipalidad debiera de saber sobre la otra, y por ende nadie denuncia nada, y el agua de nuestros lagos y r\u00edos se contin\u00faa contaminando.<\/p>\n<p style=\"text-align: justify;\">Y acontece tambi\u00e9n que: es la Municipalidad o la Provincia, la que, ante su determinaci\u00f3n de consolidar una obra p\u00fablica vinculada al caudal h\u00eddrico de los lagos o r\u00edos, le solicita a la AIC la realizaci\u00f3n de un an\u00e1lisis t\u00e9cnico y del impacto ambiental de la obra, y tambi\u00e9n en paralelo le solicita la asignaci\u00f3n de los fondos de las regal\u00edas hidroenerg\u00e9ticas para su financiaci\u00f3n; obra que, una vez analizada y aprobada por la AIC, como entidad administradora le gira los fondos para su construcci\u00f3n; y es la Municipalidad o la Provincia, la que, con la anuencia t\u00e9cnica y ambiental de la AIC, formula la debida licitaci\u00f3n para su construcci\u00f3n; y as\u00ed nos encontramos ante una\u00a0 compleja tercerizaci\u00f3n en la administraci\u00f3n de los fondos p\u00fablicos, la cual se torna aparentemente inasible de objetar o caducar en cuanto a sus aspectos legales se refiere, ya que todos los pasos institucionales o legales obligados por la municipalidad o la provincia para consolidar la obra fueron cumplidos, y as\u00ed entonces el agua de nuestros lagos y r\u00edos se contin\u00faa contaminando.<\/p>\n<p style=\"text-align: justify;\">Cabe se\u00f1alar por fin una aclaraci\u00f3n importante: esta Asamblea no refuta ni se opone al sentido de desarrollo social y econ\u00f3mico factible y debido de labrar desde la naturaleza del agua de nuestros lagos y r\u00edos patag\u00f3nicos, sino que \u2013como lo indica nuestro sentido com\u00fan- sostenido en el Art\u00edculo 41 de la Constituci\u00f3n Nacional\u2013 nos debemos al hecho de que todos los habitantes gozamos del derecho a un ambiente sano, equilibrado, apto para el desarrollo humano, y para que las actividades productivas satisfagan las necesidades presentes sin comprometer las de las generaciones futuras; y tenemos el deber de preservarlo. Con tal principio obramos y obraremos hasta recomponer cada uno de los focos contaminantes que hoy degradan la sanidad de nuestros lagos y r\u00edos Limay, Neuqu\u00e9n y Negro.<\/p>\n<p style=\"text-align: justify;\">Conclusiones:<br \/>\nSobre estos antecedentes, la Asamblea determin\u00f3 iniciar la redacci\u00f3n de un recurso de amparo y \/ o denuncia penal ante el o los responsables por el no funcionamiento de la planta de tratamiento de las cloacas de Viedma, a ser formulado por el equipo de abogados que integran esta Asamblea.<br \/>\nSe decidi\u00f3 tambi\u00e9n continuar la recolecci\u00f3n de firmas y prestaci\u00f3n de charlas a vecinos, docentes, estudiantes y p\u00fablico en general al respecto la contaminaci\u00f3n que afecta nuestros r\u00edos; con la tarea de contactar e integrar a esta Asamblea a vecinos localizados en el \u00e1mbito del Lago Nahuel Huapi y en cada uno de los poblados y ciudades ribere\u00f1as a los r\u00edos Limay, Neuqu\u00e9n y Negro, informarlos sobre los principios y objetivos de esta Asamblea; y a la vez realizar desde los mismos un \u201crelevamiento ciudadano\u201d sobre el sistema de saneamiento cloacal y de las industrias asentadas en su propia localidad.<br \/>\nFinalmente, la Asamblea decidi\u00f3 hacerse presente en el acto de inaguraci\u00f3n del muelle nuevo de Viedma \u00abAntonio Pelle\u201d, a fin de acompa\u00f1ar la memoria de quien no solamente fuera un precursor por los derechos de los trabajadores de la Provincia de R\u00edo Negro y de la Patagonia, sino que tambi\u00e9n en reconocimiento a su noble oficio de carpintero naval, tarea que ense\u00f1\u00f3 a muchos de nosotros, y quien sin dudas hoy estar\u00eda acompa\u00f1ando el prop\u00f3sito de nuestra Asamblea.<br \/>\nAnunciamos tambi\u00e9n que nuestra pr\u00f3xima Asamblea se realizar\u00e1 el s\u00e1bado 31 de mayo a las 15 horas, en el Centro Escuela Media \u2013CEM 4\u2013 de Viedma (ubicada dos cuadras detr\u00e1s del Casino).<\/p>\n<p style=\"text-align: justify;\">\nVECINOS AUTOCONVOCADOS POR LA SANIDAD DE LOS RIOS LIMAY, NEUQU\u00c9N Y NEGRO<br \/>\nJ. J. Biedma 87 &#8211; CP 8504 &#8211; Carmen de Patagones &#8211; 02920-464222 &#8211; unopatun@rnonline.com.ar<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viedma (Asamblea de Ciudadanos Autoconvocados por la Sanidad de los r\u00edos Limay, Neuqu\u00e9n y Negro).\u00a0El d\u00eda 17 de mayo se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1,3],"tags":[88,89],"class_list":["post-2072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-ong","tag-aic","tag-dpa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conclusiones de los temas tratados en la Asamblea de Ciudadanos Autoconvocados por la Sanidad de los R\u00edos Limay, Neuqu\u00e9n y Negro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conclusiones de los temas tratados en la Asamblea de Ciudadanos Autoconvocados por la Sanidad de los R\u00edos Limay, Neuqu\u00e9n y Negro\" \/>\n<meta property=\"og:description\" content=\"Viedma (Asamblea de Ciudadanos Autoconvocados por la Sanidad de los r\u00edos Limay, Neuqu\u00e9n y Negro).\u00a0El d\u00eda 17 de mayo se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg\" \/>\n<meta property=\"article:published_time\" content=\"2008-05-17T17:15:10+00:00\" \/>\n<meta name=\"author\" content=\"Patagonia Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\\\/\"},\"author\":{\"name\":\"Patagonia Ambiental\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\"},\"headline\":\"Conclusiones de los temas tratados en la Asamblea de Ciudadanos Autoconvocados por la Sanidad de los R\u00edos Limay, Neuqu\u00e9n y Negro\",\"datePublished\":\"2008-05-17T17:15:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\\\/\"},\"wordCount\":2743,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"AIC\",\"DPA\"],\"articleSection\":[\"Noticias\",\"ONG\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\\\/\",\"name\":\"Conclusiones de los temas tratados en la Asamblea de Ciudadanos Autoconvocados por la Sanidad de los R\u00edos Limay, Neuqu\u00e9n y Negro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2008-05-17T17:15:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conclusiones de los temas tratados en la Asamblea de Ciudadanos Autoconvocados por la Sanidad de los R\u00edos Limay, Neuqu\u00e9n y Negro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\",\"name\":\"Patagonia Ambiental\",\"description\":\"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\",\"https:\\\/\\\/www.facebook.com\\\/share\\\/1C1V8Gv9BX\\\/?mibextid=qi2Omg\",\"@patagoniambiental\",\"https:\\\/\\\/youtube.com\\\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conclusiones de los temas tratados en la Asamblea de Ciudadanos Autoconvocados por la Sanidad de los R\u00edos Limay, Neuqu\u00e9n y Negro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/","og_locale":"es_ES","og_type":"article","og_title":"Conclusiones de los temas tratados en la Asamblea de Ciudadanos Autoconvocados por la Sanidad de los R\u00edos Limay, Neuqu\u00e9n y Negro","og_description":"Viedma (Asamblea de Ciudadanos Autoconvocados por la Sanidad de los r\u00edos Limay, Neuqu\u00e9n y Negro).\u00a0El d\u00eda 17 de mayo se [&hellip;]","og_url":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_author":"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","article_published_time":"2008-05-17T17:15:10+00:00","author":"Patagonia Ambiental","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/"},"author":{"name":"Patagonia Ambiental","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d"},"headline":"Conclusiones de los temas tratados en la Asamblea de Ciudadanos Autoconvocados por la Sanidad de los R\u00edos Limay, Neuqu\u00e9n y Negro","datePublished":"2008-05-17T17:15:10+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/"},"wordCount":2743,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/#primaryimage"},"thumbnailUrl":"","keywords":["AIC","DPA"],"articleSection":["Noticias","ONG"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/","url":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/","name":"Conclusiones de los temas tratados en la Asamblea de Ciudadanos Autoconvocados por la Sanidad de los R\u00edos Limay, Neuqu\u00e9n y Negro","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/#primaryimage"},"thumbnailUrl":"","datePublished":"2008-05-17T17:15:10+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/conclusiones-de-los-temas-tratados-en-la-asamblea-de-ciudadanos-autoconvocados-por-la-sanidad-de-los-rios-limay-neuquen-y-negro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"Conclusiones de los temas tratados en la Asamblea de Ciudadanos Autoconvocados por la Sanidad de los R\u00edos Limay, Neuqu\u00e9n y Negro"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d","name":"Patagonia Ambiental","description":"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.","sameAs":["http:\/\/www.patagoniambiental.com.ar","https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","@patagoniambiental","https:\/\/youtube.com\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/2072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=2072"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/2072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=2072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=2072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=2072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}