{"id":27695,"date":"2017-04-18T19:00:58","date_gmt":"2017-04-18T22:00:58","guid":{"rendered":"http:\/\/patagoniambiental.com.ar\/info\/?p=27695"},"modified":"2017-04-18T10:39:29","modified_gmt":"2017-04-18T13:39:29","slug":"plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/","title":{"rendered":"Plan Castello: mejoras en el sistema de cloacas para General Conesa y Luis Beltr\u00e1n"},"content":{"rendered":"<p class=\"x_MsoNormal\"><i>General Conesa.-A trav\u00e9s del Plan Castello, el Gobierno de R\u00edo Negro proyecta expandir la cobertura del servicio de cloacas para los pr\u00f3ximos 20 a\u00f1os en General Conesa y Luis Beltr\u00e1n.<\/i><\/p>\n<p class=\"x_MsoNormal\"><!--more--><\/p>\n<p class=\"x_MsoNormal\">Las obras est\u00e1n incluidas en los Planes Directores de Desag\u00fces Pluviales de ambas localidades y prev\u00e9n abastecer de este servicio a unos 20.000 habitantes proyectados al a\u00f1o 2037, mejorando la calidad de vida de las familias.<\/p>\n<p class=\"x_MsoNormal\">Los trabajos se ejecutar\u00e1n si el Plan Castello, que est\u00e1 siendo analizado en el seno de la Legislatura, es aprobado por los parlamentarios rionegrinos.<\/p>\n<p class=\"x_MsoNormal\">En los dos casos se busca expandir la cobertura y asegurar el vuelco al cuerpo receptor, con los par\u00e1metros m\u00e1ximos de descarga exigidos por la legislaci\u00f3n vigente.<\/p>\n<p class=\"x_MsoNormal\">En el caso de Luis Beltr\u00e1n, la obra comprende redes colectoras domiciliarias, colectores troncales, la Estaci\u00f3n de Bombeo N\u00ba 1, la remodelaci\u00f3n de la actual estaci\u00f3n elevadora, la impulsi\u00f3n a planta depuradora y el sistema de lagunas facultativas. El proyecto est\u00e1 dise\u00f1ado para abastecer a m\u00e1s de 7.400 habitantes.<\/p>\n<p class=\"x_MsoNormal\">En tanto, en el caso de General Conesa, la obra comprende la ejecuci\u00f3n de redes colectoras, colectores troncales y conexiones domiciliarias. El objetivo es abastecer a m\u00e1s de 10.000 habitantes.<\/p>\n<p><b><span lang=\"ES-AR\">Fuente: GOBIERNO DE R\u00cdO NEGRO<\/span><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>General Conesa.-A trav\u00e9s del Plan Castello, el Gobierno de R\u00edo Negro proyecta expandir la cobertura del servicio de cloacas para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[14],"tags":[],"class_list":["post-27695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rio-negro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Plan Castello: mejoras en el sistema de cloacas para General Conesa y Luis Beltr\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan Castello: mejoras en el sistema de cloacas para General Conesa y Luis Beltr\u00e1n\" \/>\n<meta property=\"og:description\" content=\"General Conesa.-A trav\u00e9s del Plan Castello, el Gobierno de R\u00edo Negro proyecta expandir la cobertura del servicio de cloacas para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-18T22:00:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2017\/04\/nofoto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"924\" \/>\n\t<meta property=\"og:image:height\" content=\"616\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patagonia Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\\\/\"},\"author\":{\"name\":\"Patagonia Ambiental\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\"},\"headline\":\"Plan Castello: mejoras en el sistema de cloacas para General Conesa y Luis Beltr\u00e1n\",\"datePublished\":\"2017-04-18T22:00:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\\\/\"},\"wordCount\":234,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/nofoto.jpg\",\"articleSection\":[\"R\u00edo Negro\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\\\/\",\"name\":\"Plan Castello: mejoras en el sistema de cloacas para General Conesa y Luis Beltr\u00e1n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/nofoto.jpg\",\"datePublished\":\"2017-04-18T22:00:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\\\/#primaryimage\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/nofoto.jpg\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/nofoto.jpg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan Castello: mejoras en el sistema de cloacas para General Conesa y Luis Beltr\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\",\"name\":\"Patagonia Ambiental\",\"description\":\"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\",\"https:\\\/\\\/www.facebook.com\\\/share\\\/1C1V8Gv9BX\\\/?mibextid=qi2Omg\",\"@patagoniambiental\",\"https:\\\/\\\/youtube.com\\\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Plan Castello: mejoras en el sistema de cloacas para General Conesa y Luis Beltr\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/","og_locale":"es_ES","og_type":"article","og_title":"Plan Castello: mejoras en el sistema de cloacas para General Conesa y Luis Beltr\u00e1n","og_description":"General Conesa.-A trav\u00e9s del Plan Castello, el Gobierno de R\u00edo Negro proyecta expandir la cobertura del servicio de cloacas para [&hellip;]","og_url":"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_author":"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","article_published_time":"2017-04-18T22:00:58+00:00","og_image":[{"width":924,"height":616,"url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2017\/04\/nofoto.jpg","type":"image\/jpeg"}],"author":"Patagonia Ambiental","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/"},"author":{"name":"Patagonia Ambiental","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d"},"headline":"Plan Castello: mejoras en el sistema de cloacas para General Conesa y Luis Beltr\u00e1n","datePublished":"2017-04-18T22:00:58+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/"},"wordCount":234,"commentCount":0,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2017\/04\/nofoto.jpg","articleSection":["R\u00edo Negro"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/","url":"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/","name":"Plan Castello: mejoras en el sistema de cloacas para General Conesa y Luis Beltr\u00e1n","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2017\/04\/nofoto.jpg","datePublished":"2017-04-18T22:00:58+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/#primaryimage","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2017\/04\/nofoto.jpg","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2017\/04\/nofoto.jpg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/plan-castello-mejoras-en-el-sistema-de-cloacas-para-general-conesa-y-luis-beltran\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"Plan Castello: mejoras en el sistema de cloacas para General Conesa y Luis Beltr\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d","name":"Patagonia Ambiental","description":"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.","sameAs":["http:\/\/www.patagoniambiental.com.ar","https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","@patagoniambiental","https:\/\/youtube.com\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/27695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=27695"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/27695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media\/27696"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=27695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=27695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=27695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}