{"id":41847,"date":"2018-02-05T09:00:05","date_gmt":"2018-02-05T12:00:05","guid":{"rendered":"http:\/\/patagoniambiental.com.ar\/info\/?p=41847"},"modified":"2018-02-04T21:14:52","modified_gmt":"2018-02-05T00:14:52","slug":"ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/","title":{"rendered":"Ponele onda: 10 ideas para reciclar con cosas que ya ten\u00e9s en casa"},"content":{"rendered":"<div class=\"entry-content clearfix\">\n<div class=\"entry-body\">\n<div>\n<p>Cada vez son m\u00e1s los que se animan a dise\u00f1ar sus propios muebles y redecorar el hogar con originales ideas hechas por uno mismo.<\/p>\n<div class=\"teads-inread sm-screen\">\n<div><\/div>\n<\/div>\n<p>Hay algunas opciones que ya vienen prefabricadas, y de lo contrario, armarlos desde el inicio no suele ser muy complicado. Hay muchos modelos y la complejidad var\u00eda de acuerdo al dise\u00f1o, el l\u00edmite se lo pone uno mismo y su imaginaci\u00f3n.<\/p>\n<div>\n<figure class=\"image\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.rosario3.com\/export\/sites\/rosario3\/img\/2018\/02\/01\/deco_1_x2x.jpg_828631007.jpg\" alt=\"\" hspace=\"5\" vspace=\"5\" \/><figcaption><\/figcaption><\/figure>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Reciclar no s\u00f3lo ayuda al medio ambiente, tambi\u00e9n es bueno para tu bolsillo.Te dejamos algunas ideas interesantes para convertir muebles viejos en verdaderos tesoros:<\/p>\n<p>&nbsp;<\/p>\n<p><b>1- Mesa de caf\u00e9 con cajones de verduler\u00eda<\/b><\/p>\n<div>\n<figure class=\"image\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.rosario3.com\/export\/sites\/rosario3\/img\/2018\/02\/01\/deco_2.jpg_1994804257.jpg\" alt=\"\" hspace=\"5\" vspace=\"5\" \/><figcaption><\/figcaption><\/figure>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Si siempre miraste las cajas de madera con intriga, imaginando en qu\u00e9 podr\u00edan convertirse, esta es tu oportunidad de construir una mesa ratona con cajones de verduler\u00eda.<\/p>\n<p>Dale un toque r\u00fastico a tu living\u00a0con madera reciclada. Esta mesa adem\u00e1s de bonita es funcional, ya que los cajones se convierten en estantes para guardar revistas, floreros y dem\u00e1s elementos decorativos.<\/p>\n<p>&nbsp;<\/p>\n<p><b>2- Escalera de madera a estanter\u00eda r\u00fastica<\/b><\/p>\n<div>\n<figure class=\"image\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.rosario3.com\/export\/sites\/rosario3\/img\/2018\/02\/01\/deco_3.jpg_249964717.jpg\" alt=\"\" hspace=\"5\" vspace=\"5\" \/><figcaption><\/figcaption><\/figure>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Si ya no conf\u00edas en tu escalera de madera, pod\u00e9s darle una nueva vida agregando estantes y decor\u00e1ndola.<\/p>\n<p>\u00bfC\u00f3mo hacer una estanter\u00eda con una escalera? Muy f\u00e1cil: abrir\u00a0la escalera de dos hojas y colocar\u00a0maderas a modo de estante entre los escalones. Para asegurar que no se muevan, atornillar\u00a0los estantes a los escalones.<\/p>\n<p>Pod\u00e9s darle una terminaci\u00f3n r\u00fastica simplemente barnizando la estanter\u00eda y colocando en los estantes libros antiguos, planchas de hierro y algunas plantas.<\/p>\n<p>&nbsp;<\/p>\n<p><b>3- Biblioteca vintage con cajones de fruta<\/b><\/p>\n<div>\n<figure class=\"image\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.rosario3.com\/export\/sites\/rosario3\/img\/2018\/02\/01\/deco_4.jpg_993300317.jpg\" alt=\"\" hspace=\"5\" vspace=\"5\" \/><figcaption><\/figcaption><\/figure>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Dale a tu casa un look campestre y vintage, creando una estanter\u00eda con cajones de verduler\u00eda para colocar en cualquier lugar de tu casa.<\/p>\n<p>Con algunos cajones de fruta, pintados con una t\u00e9cnica r\u00fastica y algunos tornillos para sujetarlos, pod\u00e9s convertir algo cotidiano en una pieza fant\u00e1stica.<\/p>\n<p>Para darle una mejor terminaci\u00f3n, apoyar\u00a0una madera lustrada en la parte superior, y crear un espacio para los\u00a0portarretratos y jarrones.<\/p>\n<p>&nbsp;<\/p>\n<p><b>4- De cuna a escritorio moderno<\/b><\/p>\n<div>\n<figure class=\"image\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.rosario3.com\/export\/sites\/rosario3\/img\/2018\/02\/01\/deco_5.jpg_610855660.jpg\" alt=\"\" hspace=\"5\" vspace=\"5\" \/><figcaption><\/figcaption><\/figure>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Si no quer\u00e9s\u00a0despedirte de una\u00a0cuna, convertila\u00a0en un \u00fatil escritorio con estante.<\/p>\n<p>Para esto vas a necesitar desarmarla cuidadosamente, retirando los barrales de uno de sus lados. A continuaci\u00f3n pintarla o aplicar\u00a0barniz para un acabado prolijo y luego apoyar\u00a0un vidrio grueso sobre los barrales restantes.<\/p>\n<p>Con la parrilla de la cama para beb\u00e9s podr\u00e1s crear un c\u00f3modo estante para organizar tus art\u00edculos de oficina, libros y papeles. Si la cuna tiene dos parrillas, pod\u00e9s colocar cajas decoradas o canastas y tener m\u00e1s espacio de guardado.<\/p>\n<p>&nbsp;<\/p>\n<p><b>5- Mesa de caf\u00e9 industrial con pallets<\/b><\/p>\n<div>\n<figure class=\"image\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.rosario3.com\/export\/sites\/rosario3\/img\/2018\/02\/01\/deco_6.jpg_1164151702.jpg\" alt=\"\" hspace=\"5\" vspace=\"5\" \/><figcaption><\/figcaption><\/figure>\n<\/div>\n<p>&nbsp;<\/p>\n<p>La moda industrial est\u00e1 in: metales oxidados, madera reciclada, luminarias inspiradas en las viejas f\u00e1bricas y piezas de decoraci\u00f3n antiguas.<\/p>\n<p>Renov\u00e1 tu living con una mesa ratona r\u00fastica creada con madera reciclada y hierro. Decor\u00e1 con flores frescas y guard\u00e1 en el estante tus revistas favoritas.<\/p>\n<p>Combinada con sillones de l\u00edneas limpias y telas coloridas en almohadones y cortinas, esta mesa creada a partir de dos pallets y cuatro patas de hierro es sencilla y funcional.<\/p>\n<p>&nbsp;<\/p>\n<p><b>6- Mesa de patio con hielera incluida<\/b><\/p>\n<div>\n<figure class=\"image\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.rosario3.com\/export\/sites\/rosario3\/img\/2018\/02\/01\/deco_7.jpg_98086157.jpg\" alt=\"\" hspace=\"5\" vspace=\"5\" \/><figcaption><\/figcaption><\/figure>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Ideal para una reuni\u00f3n familiar en verano o relajarse en la tarde, esta mesa de patio con hielera incluida es un proyecto f\u00e1cil. El ejemplo que te presentamos fue construido desde cero, pero pod\u00e9s tomar esta genial idea y recrearla sin necesidad de tener herramientas tan espec\u00edficas.<\/p>\n<p>Utilizando macetas y una sierra es sencillo convertir una mesa de patio que ya est\u00e9 viejita en una pieza muy \u00fatil. Un proyecto de fin de semana que te permitir\u00e1 conservar las bebidas bien frescas en el verano, o crear un \u00e1rea verde plantando flores coloridas en las macetas.<\/p>\n<p>&nbsp;<\/p>\n<p><b>7- C\u00f3modo banco a partir de dos sillas<\/b><\/p>\n<div>\n<figure class=\"image\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.rosario3.com\/export\/sites\/rosario3\/img\/2018\/02\/01\/deco_8_1.jpg_537065498.jpg\" alt=\"\" hspace=\"5\" vspace=\"5\" \/><figcaption><\/figcaption><\/figure>\n<\/div>\n<p>&nbsp;<\/p>\n<p>\u00bfTen\u00e9s algunas sillas que ya han visto sus mejores d\u00edas? \u00a1No las tires! Con algunas maderas, pintura y unos lindos almohadones pod\u00e9s construir un banco hermoso.<\/p>\n<p>Cortar\u00a0los asientos de dos sillas del mismo juego, dejando sus patas traseras y el respaldo. Crear\u00a0un marco rectangular con maderas, que tenga el largo deseado y el ancho de los respaldos. Atornillar\u00a0los respaldos al marco y a\u00f1adir\u00a0con clavos maderas para crear una parrilla.<\/p>\n<p>Dale rienda suelta a tu creatividad y combina los almohadones con la pintura. Para un look playero, pintar\u00a0la madera de color azul y utilizar almohadones rayados de color blanco y amarillo. Para una onda rom\u00e1ntica, pintar\u00a0la madera de color marfil o rosa p\u00e1lido y a\u00f1adir almohadones floreados.<\/p>\n<p>&nbsp;<\/p>\n<p><b>8- Cubierta de monedas para renovar superficies<\/b><\/p>\n<div>\n<figure class=\"image\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.rosario3.com\/export\/sites\/rosario3\/img\/2018\/02\/01\/deco_9.jpg_1830727274.jpg\" alt=\"\" hspace=\"5\" vspace=\"5\" \/><figcaption><\/figcaption><\/figure>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Para los coleccionistas que deseen exhibir sus tesoros de una manera divertida, la tendencia es crear superficies con monedas. Desde mesas a bordes de espejos, y los pisos cubiertos con centavo; son miles las posibilidades.<\/p>\n<p>Si son m\u00e1s aventurero\/a, incluso pod\u00e9s cubrir el piso de una peque\u00f1a \u00e1rea de tu casa.<\/p>\n<p>Limpiar\u00a0bien las monedas, especialmente en la cara que ser\u00e1 visible. Elegir\u00a0la superficie que te gustar\u00eda cubrir y posicionar\u00a0las monedas sobre ella, para tener una idea de la cantidad que necesitar\u00e1s.<\/p>\n<p>Adherir\u00a0una a una las monedas a la superficie con pegamento, y posteriormente lustrarlas para que se vean brillantes. El paso m\u00e1s importante para aportar durabilidad y un acabado profesional: cubrir\u00a0las monedas con resina, siguiendo cuidadosamente las instrucciones de la marca que hayas comprado en la barraca.<\/p>\n<p>&nbsp;<\/p>\n<p><b>9- Respaldo para cama con una puerta<\/b><\/p>\n<div>\n<figure class=\"image\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.rosario3.com\/export\/sites\/rosario3\/img\/2018\/02\/01\/deco.png_1110515322.png\" alt=\"\" hspace=\"5\" vspace=\"5\" \/><figcaption><\/figcaption><\/figure>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Tal vez remodelaste alguna parte de tu casa y est\u00e1s pensando en deshacerte de una puerta vieja que ya no sirve para su prop\u00f3sito.<\/p>\n<p>Una buena idea es crear un respaldo para la cama a partir de una puerta en desuso. Mientras m\u00e1s adornada sea la estructura, mejor el efecto. Si tiene herrajes o cerraduras antiguas, quitar\u00a0la pintura que pueden tener adherida y lustrarlas para resaltar los detalles.<\/p>\n<p>Dejar\u00a0la pintura actual para un efecto vintage, o lijar y pasar\u00a0una capa de protector para madera para un look m\u00e1s refinado.<\/p>\n<p>&nbsp;<\/p>\n<p><b>10- Cajonera a mueble de cocina<\/b><\/p>\n<div>\n<figure class=\"image\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.rosario3.com\/export\/sites\/rosario3\/img\/2018\/02\/01\/deco_11.jpg_105796636.jpg\" alt=\"\" hspace=\"5\" vspace=\"5\" \/><figcaption><\/figcaption><\/figure>\n<\/div>\n<p>&nbsp;<\/p>\n<p>\u00bfCocina peque\u00f1a? No hay problema, a partir de una c\u00f3moda o cajonera que ya no se use pod\u00e9s construir un mueble para cocina muy funcional.<\/p>\n<p>El dise\u00f1o final depender\u00e1 de la c\u00f3moda que tengas y las necesidades de guardado de tu cocina, pero algunos tips son:<\/p>\n<p>&#8211; Conservar algunos cajones para organizar los cubiertos.<\/p>\n<p>&#8211; A\u00f1adir\u00a0un barral para colgar el rollo de papel de cocina o ganchos con utensilios.<\/p>\n<p>&#8211; Colocar\u00a0estantes si necesitas mayor superficie.<\/p>\n<p>&#8211; Agregar\u00a0canastas en uno de los lados para guardar frutas y verduras.<\/p>\n<p>&#8211; Para que no luzca como un mueble de dormitorio, pintarla del mismo color que el resto de los estantes en tu cocina y colocar una madera lustrada en la parte superior.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"entry-data stop-vertical-share clearfix\">\n<div class=\"entry-single-options\">Fuente: https:\/\/www.rosario3.com\/trendy\/Ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa-20180201-0051.html<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cada vez son m\u00e1s los que se animan a dise\u00f1ar sus propios muebles y redecorar el hogar con originales ideas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":41848,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[53],"tags":[],"class_list":["post-41847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ponele onda: 10 ideas para reciclar con cosas que ya ten\u00e9s en casa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ponele onda: 10 ideas para reciclar con cosas que ya ten\u00e9s en casa\" \/>\n<meta property=\"og:description\" content=\"Cada vez son m\u00e1s los que se animan a dise\u00f1ar sus propios muebles y redecorar el hogar con originales ideas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-05T12:00:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2018\/02\/reciclar-deco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"428\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patagonia Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\\\/\"},\"author\":{\"name\":\"Patagonia Ambiental\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\"},\"headline\":\"Ponele onda: 10 ideas para reciclar con cosas que ya ten\u00e9s en casa\",\"datePublished\":\"2018-02-05T12:00:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\\\/\"},\"wordCount\":1213,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/reciclar-deco.jpg\",\"articleSection\":[\"General\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\\\/\",\"name\":\"Ponele onda: 10 ideas para reciclar con cosas que ya ten\u00e9s en casa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/reciclar-deco.jpg\",\"datePublished\":\"2018-02-05T12:00:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/reciclar-deco.jpg\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/reciclar-deco.jpg\",\"width\":760,\"height\":428},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ponele onda: 10 ideas para reciclar con cosas que ya ten\u00e9s en casa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\",\"name\":\"Patagonia Ambiental\",\"description\":\"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\",\"https:\\\/\\\/www.facebook.com\\\/share\\\/1C1V8Gv9BX\\\/?mibextid=qi2Omg\",\"@patagoniambiental\",\"https:\\\/\\\/youtube.com\\\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ponele onda: 10 ideas para reciclar con cosas que ya ten\u00e9s en casa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/","og_locale":"es_ES","og_type":"article","og_title":"Ponele onda: 10 ideas para reciclar con cosas que ya ten\u00e9s en casa","og_description":"Cada vez son m\u00e1s los que se animan a dise\u00f1ar sus propios muebles y redecorar el hogar con originales ideas [&hellip;]","og_url":"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_author":"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","article_published_time":"2018-02-05T12:00:05+00:00","og_image":[{"width":760,"height":428,"url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2018\/02\/reciclar-deco.jpg","type":"image\/jpeg"}],"author":"Patagonia Ambiental","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/"},"author":{"name":"Patagonia Ambiental","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d"},"headline":"Ponele onda: 10 ideas para reciclar con cosas que ya ten\u00e9s en casa","datePublished":"2018-02-05T12:00:05+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/"},"wordCount":1213,"commentCount":0,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2018\/02\/reciclar-deco.jpg","articleSection":["General"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/","url":"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/","name":"Ponele onda: 10 ideas para reciclar con cosas que ya ten\u00e9s en casa","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2018\/02\/reciclar-deco.jpg","datePublished":"2018-02-05T12:00:05+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/#primaryimage","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2018\/02\/reciclar-deco.jpg","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2018\/02\/reciclar-deco.jpg","width":760,"height":428},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/ponele-onda-10-ideas-para-reciclar-con-cosas-que-ya-tenes-en-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"Ponele onda: 10 ideas para reciclar con cosas que ya ten\u00e9s en casa"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d","name":"Patagonia Ambiental","description":"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.","sameAs":["http:\/\/www.patagoniambiental.com.ar","https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","@patagoniambiental","https:\/\/youtube.com\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/41847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=41847"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/41847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media\/41848"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=41847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=41847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=41847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}