{"id":61737,"date":"2019-06-07T07:00:55","date_gmt":"2019-06-07T10:00:55","guid":{"rendered":"http:\/\/patagoniambiental.com.ar\/info\/?p=61737"},"modified":"2019-06-06T15:08:07","modified_gmt":"2019-06-06T18:08:07","slug":"neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/","title":{"rendered":"Neuquen: Plantas y compost, en el D\u00eda Mundial del Medioambiente"},"content":{"rendered":"<article id=\"article-post\" class=\"cat-rojo\">\n<header>\n<div class=\"row\">\n<div class=\"col-xs-12\">\n<p class=\"title\">Neuqu\u00e9n.- En el D\u00eda Mundial del Medioambiente se ense\u00f1\u00f3 a fabricar abono org\u00e1nico y se regalaron composteras y lombrices californianas para obtener humus para las plantas y huertos. En forma paralela y como tambi\u00e9n se celebr\u00f3 ayer el D\u00eda de la Ciudad Limpia, la Municipalidad llev\u00f3 adelante\u00a0<a class=\"agrupador\" href=\"http:\/\/www.lmneuquen.com\/actividades-a5982\" rel=\"5982\">actividades<\/a>\u00a0de limpieza y de concientizaci\u00f3n ambiental en toda la ciudad.<!--more--><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/header>\n<div class=\"head-image thumb-wrap relative\">\n<div id=\"content-gallery\">\n<div id=\"fotogaleria-Object_3184_1797\" class=\"gallery\">\n<div class=\"col2\">\n<div class=\"image itemGallery classid565169\"><a title=\"\" href=\"https:\/\/media.lmneuquen.com\/adjuntos\/195\/imagenes\/003\/652\/0003652394.jpg\"><img fetchpriority=\"high\" decoding=\"async\" title=\"Plantas y compost, en el D\u00eda Mundial del Medioambiente\" src=\"https:\/\/media.lmneuquen.com\/adjuntos\/195\/imagenes\/003\/652\/0003652394.jpg\" alt=\"Plantas y compost, en el D\u00eda Mundial del Medioambiente\" width=\"770\" height=\"433\" \/><\/a><\/p>\n<div class=\"gallery-header\"><\/div>\n<div class=\"pieFoto\"><span class=\"copyinterior\">Sebastian Fari\u00f1a Petersen<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"cuerpo\">\n<p>Las actividades sumaron a alumnos de\u00a0<a class=\"agrupador\" href=\"http:\/\/www.lmneuquen.com\/escuelas-a300\" rel=\"300\">escuelas<\/a>\u00a0en talleres organizados en el auditorio de la Municipalidad de Neuqu\u00e9n aprendiendo sobre el reciclaje de residuos, la importancia de cuidar el medioambiente y de separar en casa los h\u00famedos y secos.<\/p>\n<p>\u201cJunto con la Subsecretar\u00eda de Medio Ambiente y la subsecretar\u00eda de Limpieza Urbana estamos desplegados en toda la ciudad haciendo distintas actividades con otras instituciones de cada barrio\u201d, describi\u00f3 el secretario de Gobierno y Coordinaci\u00f3n, Marcelo Berm\u00fadez.<\/p>\n<\/div>\n<\/article>\n<article id=\"article-post\" class=\"cat-rojo\">\n<div class=\"cuerpo\">\n<p>\u201cAs\u00ed que -dijo- estamos limpiando canales y sectores de muchos\u00a0<a class=\"agrupador\" href=\"http:\/\/www.lmneuquen.com\/barrios-a1890\" rel=\"1890\">barrios<\/a>, trabajando con alumnos, haciendo tareas de concientizaci\u00f3n pero tambi\u00e9n premi\u00e1ndolos por iniciativas que llevaron adelante con sus cursos a favor de un mejor cuidado del medioambiente\u201d.<\/p>\n<h3>Fuente: La Ma\u00f1ana Neuquen<\/h3>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Neuqu\u00e9n.- En el D\u00eda Mundial del Medioambiente se ense\u00f1\u00f3 a fabricar abono org\u00e1nico y se regalaron composteras y lombrices californianas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":61738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[12,3357],"tags":[],"class_list":["post-61737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-ambiental","category-girsu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Neuquen: Plantas y compost, en el D\u00eda Mundial del Medioambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neuquen: Plantas y compost, en el D\u00eda Mundial del Medioambiente\" \/>\n<meta property=\"og:description\" content=\"Neuqu\u00e9n.- En el D\u00eda Mundial del Medioambiente se ense\u00f1\u00f3 a fabricar abono org\u00e1nico y se regalaron composteras y lombrices californianas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-07T10:00:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/06\/0003652394.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patagonia Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\\\/\"},\"author\":{\"name\":\"Patagonia Ambiental\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\"},\"headline\":\"Neuquen: Plantas y compost, en el D\u00eda Mundial del Medioambiente\",\"datePublished\":\"2019-06-07T10:00:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\\\/\"},\"wordCount\":208,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/0003652394.jpg\",\"articleSection\":[\"Agenda Ambiental\",\"GIRSU\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\\\/\",\"name\":\"Neuquen: Plantas y compost, en el D\u00eda Mundial del Medioambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/0003652394.jpg\",\"datePublished\":\"2019-06-07T10:00:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/0003652394.jpg\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/0003652394.jpg\",\"width\":770,\"height\":433},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neuquen: Plantas y compost, en el D\u00eda Mundial del Medioambiente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\",\"name\":\"Patagonia Ambiental\",\"description\":\"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\",\"https:\\\/\\\/www.facebook.com\\\/share\\\/1C1V8Gv9BX\\\/?mibextid=qi2Omg\",\"@patagoniambiental\",\"https:\\\/\\\/youtube.com\\\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Neuquen: Plantas y compost, en el D\u00eda Mundial del Medioambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/","og_locale":"es_ES","og_type":"article","og_title":"Neuquen: Plantas y compost, en el D\u00eda Mundial del Medioambiente","og_description":"Neuqu\u00e9n.- En el D\u00eda Mundial del Medioambiente se ense\u00f1\u00f3 a fabricar abono org\u00e1nico y se regalaron composteras y lombrices californianas [&hellip;]","og_url":"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_author":"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","article_published_time":"2019-06-07T10:00:55+00:00","og_image":[{"width":770,"height":433,"url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/06\/0003652394.jpg","type":"image\/jpeg"}],"author":"Patagonia Ambiental","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/"},"author":{"name":"Patagonia Ambiental","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d"},"headline":"Neuquen: Plantas y compost, en el D\u00eda Mundial del Medioambiente","datePublished":"2019-06-07T10:00:55+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/"},"wordCount":208,"commentCount":0,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/06\/0003652394.jpg","articleSection":["Agenda Ambiental","GIRSU"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/","url":"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/","name":"Neuquen: Plantas y compost, en el D\u00eda Mundial del Medioambiente","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/06\/0003652394.jpg","datePublished":"2019-06-07T10:00:55+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/#primaryimage","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/06\/0003652394.jpg","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/06\/0003652394.jpg","width":770,"height":433},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/neuquen-plantas-y-compost-en-el-dia-mundial-del-medioambiente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"Neuquen: Plantas y compost, en el D\u00eda Mundial del Medioambiente"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d","name":"Patagonia Ambiental","description":"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.","sameAs":["http:\/\/www.patagoniambiental.com.ar","https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","@patagoniambiental","https:\/\/youtube.com\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/61737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=61737"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/61737\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media\/61738"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=61737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=61737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=61737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}