{"id":62069,"date":"2019-06-28T07:00:28","date_gmt":"2019-06-28T10:00:28","guid":{"rendered":"http:\/\/patagoniambiental.com.ar\/info\/?p=62069"},"modified":"2019-06-26T12:04:00","modified_gmt":"2019-06-26T15:04:00","slug":"como-proteger-a-tu-perro-durante-el-frio","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/","title":{"rendered":"C\u00f3mo proteger a tu perro durante el fr\u00edo"},"content":{"rendered":"<article id=\"article-post\" class=\"cat-amarillo\">\n<header>\n<div class=\"row\">\n<div class=\"col-xs-12\">Si bien su cuerpo est\u00e1 preparado, hay que reforzar el abrigo, la alimentaci\u00f3n y su actividad f\u00edsica.<\/div>\n<\/div>\n<p><!--more--><\/p>\n<\/header>\n<div class=\"cuerpo\">\n<p>Si bien los perros cuentan con un pelaje que los protege de las bajas temperaturas, ellos tambi\u00e9n sufren de la llegada del fr\u00edo ya que est\u00e1n expuestos permanentemente. Por eso, hay que tomar recaudos y medidas para que nuestro amigo canino sobrelleve estos meses sin dificultades.<\/p>\n<\/div>\n<\/article>\n<p>En primer lugar, es indispensable que recubras el \u00e1rea de dormir de la mascota con alguna frazada extra. Una cobija puede resultarle de gran ayuda para evitar que tome demasiado fr\u00edo, especialmente si no estamos frente a una raza acostumbrada a este clima.<\/p>\n<article id=\"article-post\" class=\"cat-amarillo\">\n<div class=\"cuerpo\">\n<p>Tal como sucede con las personas, los perros tambi\u00e9n necesitan tan de una dosis extra de energ\u00eda para soportar las malas condiciones clim\u00e1ticas. Es importante entonces que te asegures de alimentar a tu perro con alguna comida extra, siempre y cuando lleves un estricto control de las cantidades, pues el sobrepeso puede resultar igualmente da\u00f1ino para su salud. Tambi\u00e9n hay que controlar peri\u00f3dicamente el estado del bebedero ya que puede congelarse con mucha rapidez. Procura que su agua se encuentre siempre a una temperatura ideal para ser ingerida.<\/p>\n<div class=\"teads-adCall\"><\/div>\n<p><span id=\"saysCMSEmphasisde0hl0876rp\" class=\"saysCMSEmphasis\">Cucha calentita: Es indispensable recubrir el \u00e1rea de dormir de la mascota con alguna frazada.<\/span><\/p>\n<p>Por otro lado, en esta \u00e9poca del a\u00f1o los animales acostumbran a volverse un poco perezosos, lo que puede acarrear consecuencias en su estado f\u00edsico y emocional. Debido a esto hay que motivarlos a\u00fan m\u00e1s con una peque\u00f1a dosis de ejercicio diario, que servir\u00e1 tanto para revitalizar sus m\u00fasculos como para disminuir la sensaci\u00f3n de fr\u00edo. De todas maneras, se debe prestar atenci\u00f3n al entorno en el que se desarrollen la actividad ya que algunos objetos, ante las heladas, se vuelven cortantes. Del mismo modo, es recomendable que evites aquellos sitios que presenten estacas de hielo colgando desde los techos o las terrazas, ya que un golpe puede desprenderlas con facilidad y lastimar al animal.<\/p>\n<p><strong>\u00c9poca de muda de pelo por Sergio g\u00f3mez (veterinario)<\/strong><\/p>\n<p>La muda de pelo es un proceso natural que realizan todos los mam\u00edferos, en el cual el pelo muerto se cae y es reemplazado por pelo nuevo. Es un proceso continuo que ocurre durante todo el a\u00f1o, aunque es m\u00e1s marcado al comienzo del oto\u00f1o, cuando el perro adquiere un pelo grueso y m\u00e1s denso que lo protege del fr\u00edo. En primavera, pierde el de m\u00e1s esperos y lo cambia por un pelo m\u00e1s fino, pudiendo soportar mejor las altas temperaturas del verano. En los perros de pelo largo y en los que viven afuera este cambio es m\u00e1s evidente, mientras que, debido a la calefacci\u00f3n, en las \u00e9pocas de fr\u00edo en los perros que viven adentro y en aquellos de pelo corto, la muda puede ser constante y pareja durante todo el a\u00f1o. Hay razas en las que, a pesar del proceso de muda, es necesario realizar el corte de pelo cuando comienza el calor.<\/p>\n<p>Fuente: La Ma\u00f1ana Neuquen<\/p>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Si bien su cuerpo est\u00e1 preparado, hay que reforzar el abrigo, la alimentaci\u00f3n y su actividad f\u00edsica.<\/p>\n","protected":false},"author":2,"featured_media":59043,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[53],"tags":[],"class_list":["post-62069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>C\u00f3mo proteger a tu perro durante el fr\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo proteger a tu perro durante el fr\u00edo\" \/>\n<meta property=\"og:description\" content=\"Si bien su cuerpo est\u00e1 preparado, hay que reforzar el abrigo, la alimentaci\u00f3n y su actividad f\u00edsica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-28T10:00:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/02\/thumbnail_Mascotas3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"903\" \/>\n\t<meta property=\"og:image:height\" content=\"690\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patagonia Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/como-proteger-a-tu-perro-durante-el-frio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/como-proteger-a-tu-perro-durante-el-frio\\\/\"},\"author\":{\"name\":\"Patagonia Ambiental\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\"},\"headline\":\"C\u00f3mo proteger a tu perro durante el fr\u00edo\",\"datePublished\":\"2019-06-28T10:00:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/como-proteger-a-tu-perro-durante-el-frio\\\/\"},\"wordCount\":538,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/como-proteger-a-tu-perro-durante-el-frio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/thumbnail_Mascotas3.jpg\",\"articleSection\":[\"General\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/como-proteger-a-tu-perro-durante-el-frio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/como-proteger-a-tu-perro-durante-el-frio\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/como-proteger-a-tu-perro-durante-el-frio\\\/\",\"name\":\"C\u00f3mo proteger a tu perro durante el fr\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/como-proteger-a-tu-perro-durante-el-frio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/como-proteger-a-tu-perro-durante-el-frio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/thumbnail_Mascotas3.jpg\",\"datePublished\":\"2019-06-28T10:00:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/como-proteger-a-tu-perro-durante-el-frio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/como-proteger-a-tu-perro-durante-el-frio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/como-proteger-a-tu-perro-durante-el-frio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/thumbnail_Mascotas3.jpg\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/thumbnail_Mascotas3.jpg\",\"width\":785,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/como-proteger-a-tu-perro-durante-el-frio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo proteger a tu perro durante el fr\u00edo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\",\"name\":\"Patagonia Ambiental\",\"description\":\"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\",\"https:\\\/\\\/www.facebook.com\\\/share\\\/1C1V8Gv9BX\\\/?mibextid=qi2Omg\",\"@patagoniambiental\",\"https:\\\/\\\/youtube.com\\\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"C\u00f3mo proteger a tu perro durante el fr\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo proteger a tu perro durante el fr\u00edo","og_description":"Si bien su cuerpo est\u00e1 preparado, hay que reforzar el abrigo, la alimentaci\u00f3n y su actividad f\u00edsica.","og_url":"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_author":"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","article_published_time":"2019-06-28T10:00:28+00:00","og_image":[{"width":903,"height":690,"url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/02\/thumbnail_Mascotas3.jpg","type":"image\/jpeg"}],"author":"Patagonia Ambiental","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/"},"author":{"name":"Patagonia Ambiental","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d"},"headline":"C\u00f3mo proteger a tu perro durante el fr\u00edo","datePublished":"2019-06-28T10:00:28+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/"},"wordCount":538,"commentCount":0,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/02\/thumbnail_Mascotas3.jpg","articleSection":["General"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/","url":"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/","name":"C\u00f3mo proteger a tu perro durante el fr\u00edo","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/02\/thumbnail_Mascotas3.jpg","datePublished":"2019-06-28T10:00:28+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/#primaryimage","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/02\/thumbnail_Mascotas3.jpg","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/02\/thumbnail_Mascotas3.jpg","width":785,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/como-proteger-a-tu-perro-durante-el-frio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo proteger a tu perro durante el fr\u00edo"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d","name":"Patagonia Ambiental","description":"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.","sameAs":["http:\/\/www.patagoniambiental.com.ar","https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","@patagoniambiental","https:\/\/youtube.com\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/62069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=62069"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/62069\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media\/59043"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=62069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=62069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=62069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}