{"id":63264,"date":"2019-09-25T07:00:54","date_gmt":"2019-09-25T10:00:54","guid":{"rendered":"http:\/\/patagoniambiental.com.ar\/info\/?p=63264"},"modified":"2019-09-23T13:39:56","modified_gmt":"2019-09-23T16:39:56","slug":"el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/","title":{"rendered":"El reciclaje alcanz\u00f3 el 60% de la basura domiciliaria"},"content":{"rendered":"<article id=\"article-post\" class=\"cat-rojo\">\n<header>\n<div class=\"row\">\n<div class=\"col-xs-12\">\n<h1 class=\"title\"><span style=\"font-size: 16px;\">Neuquen.-A tres a\u00f1os de la puesta en pr\u00e1ctica, el sistema sigue mejorando.<\/span><\/h1>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<\/header>\n<div class=\"head-image thumb-wrap relative\">\n<div id=\"content-gallery\">\n<div id=\"fotogaleria-Object_3184_1797\" class=\"gallery\">\n<div class=\"col2\">\n<div class=\"image itemGallery classid579313\"><a title=\"\" href=\"https:\/\/media.lmneuquen.com\/adjuntos\/195\/imagenes\/004\/120\/0004120211.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"\" title=\"El reciclaje alcanz\u00f3 el 60% de la basura domiciliaria\" src=\"https:\/\/media.lmneuquen.com\/adjuntos\/195\/imagenes\/004\/120\/0004120211.jpg\" alt=\"El reciclaje alcanz\u00f3 el 60% de la basura domiciliaria\" width=\"540\" height=\"306\" \/><\/a><\/p>\n<div class=\"gallery-header\"><\/div>\n<div class=\"pieFoto\"><span class=\"copyinterior\">Sebastian Fari\u00f1a Petersen<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"clearfix\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"cuerpo\">\n<p><strong>Alejandro Olivera &#8211; olivera@lmneuquen.com.ar<\/strong><\/p>\n<\/div>\n<\/article>\n<p>&nbsp;<\/p>\n<article id=\"article-post\" class=\"cat-rojo\">\n<div class=\"cuerpo\">\n<p>A tres a\u00f1os de su lanzamiento, la separaci\u00f3n de residuos domiciliarios en origen crece. Se recupera m\u00e1s del 60 por ciento de la\u00a0<a class=\"agrupador\" href=\"http:\/\/www.lmneuquen.com\/basura-a344\" rel=\"344\">basura<\/a>\u00a0que se recolecta en los barrios, mientras que tambi\u00e9n hay buenos resultados con los contenedores del centro y los desechos de las empresas.<\/p>\n<\/div>\n<\/article>\n<section class=\"news-lay-3 bottom-margin lista-notas-relacionadas relacionadas-nota inbody\">\n<header><\/header>\n<div class=\"row\">\n<article class=\"item clearfix col-xs-12 col-sm-6 cat- rel-has-media\">\n<div class=\"row\">\n<div class=\"col-xs-6 col-sm-6\">\n<div class=\"media thumb-wrap relative wrapper-relacionadas\"><\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/section>\n<article id=\"article-post\" class=\"cat-rojo\">\n<div class=\"cuerpo\">\n<p>El sistema comenz\u00f3 a difundirse en enero de 2016, pero se aplic\u00f3 un a\u00f1o despu\u00e9s. Previamente, ten\u00edan que juntar un buen volumen en la planta para empezar a trabajar y darle continuidad al proyecto ambiental. La subsecretaria de Medio Ambiente de la Municipalidad, Silvia Guti\u00e9rrez, le dijo a este diario que los resultados obtenidos hasta el momento son muy buenos. \u201cLa gente est\u00e1 tomando conciencia de que se puede reciclar la basura para evitar que vaya a un relleno sanitario y, de esta manera, hacer algo positivo por la sociedad y el medioambiente\u201d, dijo.<\/p>\n<div class=\"teads-inread\">\n<div id=\"teads0\" class=\"teads-player\"><\/div>\n<\/div>\n<p>La funcionaria indic\u00f3 que la planta trabaja con los residuos secos, que se recolectan los lunes y los jueves. Se\u00f1al\u00f3 que hace una selecci\u00f3n de las mejores fracciones de los barrios, de lo que se recupera m\u00e1s de un 60 por ciento, mientras que, adem\u00e1s, separa el contenido de los contenedores verdes que hay en el centro. \u201cSon ingresos que est\u00e1n dando buenos resultados para la cooperativa\u201d, afirm\u00f3.<\/p>\n<p>Tambi\u00e9n reciben desperdicios de las grandes empresas. \u201cTodas las tardes reciben material de muy buena calidad, identificado y separado, que despu\u00e9s ac\u00e1 se revaloriza con la mano de obra\u201d, puntualiz\u00f3.<\/p>\n<p>La iniciativa de la gesti\u00f3n Quiroga persegu\u00eda tres objetivos fundamentales. El primero era reducir el impacto ambiental de la actividad humana, disminuyendo la cantidad de residuos que se enterraba en las cavas de relleno sanitario.<\/p>\n<p>El segundo era darles valor agregado a los productos reciclables a trav\u00e9s del trabajo de la cooperativa Las Emprendedoras, que clasifica los residuos en funci\u00f3n del tipo de material -pl\u00e1stico, cart\u00f3n, papel, etc.- y los compacta para luego venderlos.<\/p>\n<p>El tercero, en tanto, mejorar las condiciones laborales de las personas que trabajaban en el basural, d\u00e1ndoles las garant\u00edas necesarias para que desarrollen sus actividades de una manera segura y rentable.<\/p>\n<p>Las autoridades est\u00e1n contentas con lo que han logrado en estos tres a\u00f1os, pero no se quedan conformes. Guti\u00e9rrez adelant\u00f3 que ya est\u00e1n planificando la construcci\u00f3n de una planta de separaci\u00f3n m\u00e1s grande y la adquisici\u00f3n de nuevos equipos, lo que abrir\u00eda nuevas oportunidades laborales para los neuquinos.<\/p>\n<div id=\"embed1743_wrap\" class=\"embed_cont type_freetext\" contenteditable=\"false\" data-provider=\"YouTube\">\n<div id=\"embed1743_content\" class=\"embed_content\">\n<div id=\"embed1743_embed\"><iframe src=\"https:\/\/www.youtube.com\/embed\/2Kxt6gjNoYU?feature=oembed\" width=\"100%\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><strong>La municipalidad contra el Girsu<\/strong><\/p>\n<p>Silvia Guti\u00e9rrez, de Ambiente municipal, se manifest\u00f3 en contra del proyecto Girsu, que impulsa la Provincia. Se trata de una planta de residuos para localidades neuquinas y rionegrinas proyectada en Centenario. \u201cMe parece una propuesta sin sentido. Piensan gastar 45 millones de d\u00f3lares para hacer algo que ya estamos haciendo ac\u00e1\u201d, expres\u00f3. Critic\u00f3 que planean levantar el nuevo complejo a menos de 20 kil\u00f3metros del CAN, lo que implicar\u00eda una doble log\u00edstica y un costo de obra alto. \u201cEs un gasto que van a terminar pagando los neuquinos, cuando este complejo ambiental ya est\u00e1 pagado. La Provincia pretende generar deuda con una fantas\u00eda\u201d, indic\u00f3.<\/p>\n<p>\u201cHacer un complejo para ciudades que generan 20, 30 toneladas por d\u00eda est\u00e1 bastante fuera de lugar\u201d, concluy\u00f3.<\/p>\n<div class=\"saysCMSEmphasis\">1 tonelada de PET\u00a0<a class=\"agrupador\" href=\"http:\/\/www.lmneuquen.com\/reciclado-a6941\" rel=\"6941\">reciclado<\/a>\u00a0reemplaza a 4 barriles de petr\u00f3leo<\/div>\n<p>La comparaci\u00f3n la hicieron los responsables del CAN para remarcar el valor del reciclaje. \u201cEs un trabajo fundamental para reducir el impacto de la actividad humana sobre el ambiente\u201d.<\/p>\n<div class=\"saysCMSEmphasis\">100 toneladas mensuales recicla la planta del Can<\/div>\n<p>En el CAN consideraron que se trata de un volumen aceptable, que les permite a todos los trabajadores vivir de su sueldo. La cooperativa Las Emprendedoras est\u00e1 a cargo del reciclaje.<\/p>\n<div id=\"579312-Libre-1892380085_wrap\" class=\"embed_cont type_imagen\" contenteditable=\"false\">\n<div id=\"579312-Libre-1892380085_content\" class=\"embed_content\"><img decoding=\"async\" id=\"579312-Libre-1892380085_embed\" src=\"https:\/\/media.lmneuquen.com\/adjuntos\/195\/imagenes\/004\/120\/0004120197.jpg?0000-00-00-00-00-00\" alt=\"\" longdesc=\"https:\/\/media.lmneuquen.com\/adjuntos\/195\/imagenes\/004\/120\/0004120197.jpg?0000-00-00-00-00-00\" \/><\/div>\n<div id=\"579312-Libre-1892380085_copyright\" class=\"embed_copyright empty-epigrafe\">Sebastian Fari\u00f1a Petersen<\/div>\n<\/div>\n<p><strong>La cooperativa que la rompi\u00f3 al tomar la posta<\/strong><\/p>\n<p>La cooperativa Las Emprendedoras tom\u00f3 la posta de la planta de separaci\u00f3n de residuos en 2018, luego de que la Municipalidad diera de baja el contrato de concesi\u00f3n que ten\u00eda con otra cooperativa, denominada La Colonia. Esgrimi\u00f3 para tomar esa medida problemas de organizaci\u00f3n. En tan solo un a\u00f1o pas\u00f3 de tener diez miembros a m\u00e1s de cuarenta en el Complejo Ambiental Neuqu\u00e9n (CAN).<\/p>\n<p>Silvia Guti\u00e9rrez, de Ambiente municipal, cont\u00f3 que no ten\u00edan experiencia en el rubro, pero que de todas formas se arriesgaron, ya que vieron una oportunidad para progresar. \u201cSe hicieron cargo con mucho entusiasmo y tomaron a varias personas que hab\u00edan integrado la cooperativa que hizo el trabajo anteriormente, para que aporten su experiencia\u201d, detall\u00f3<\/p>\n<p>Se\u00f1al\u00f3 que las 40 personas que trabajan en el lugar tienen \u201cuna ocupaci\u00f3n decente, capacitaciones frecuentes, elementos de seguridad y obra social\u201d, entre otros aspectos positivos de la formalidad laboral.<\/p>\n<p>Guti\u00e9rrez indic\u00f3 que hacen el trabajo m\u00e1s dif\u00edcil, que es clasificar los residuos. \u201cEstamos trabajando con ellos desde hace m\u00e1s de un a\u00f1o, per\u00edodo en el que han tenido una muy buena performance, cada vez con mayor cantidad de volumen de residuos y m\u00e1s diversidad, buscando las alternativas dentro del mercado para valorizar y vender m\u00e1s productos\u201d, puntualiz\u00f3.<\/p>\n<p>En la actualidad, desarrollan sus actividades en dos turnos, de 6 a 13 y de 10 a 17, aunque ya est\u00e1n pensando en incorporar un turno adicional para aumentar la producci\u00f3n. Al respecto, la funcionaria aclar\u00f3 que existe la posibilidad de que se convierta en una realidad, pero aclar\u00f3 que la sociedad deber\u00eda adoptar nuevas medidas para la separaci\u00f3n de los residuos en origen.<\/p>\n<p>\u201cLa gente que trabaja ac\u00e1 sabe c\u00f3mo hacer su trabajo y son los primeros interesados en cambiar de vida. Ac\u00e1 se les dio la oportunidad que no ten\u00edan y ellos la aprovecharon para recuperar su dignidad\u201d, concluy\u00f3 Guti\u00e9rrez.<\/p>\n<div id=\"579385-Libre-1544853056_wrap\" class=\"embed_cont type_imagen\" contenteditable=\"false\">\n<div id=\"579385-Libre-1544853056_content\" class=\"embed_content\"><img decoding=\"async\" id=\"579385-Libre-1544853056_embed\" src=\"https:\/\/media.lmneuquen.com\/adjuntos\/195\/imagenes\/004\/121\/0004121163.jpg?0000-00-00-00-00-00\" alt=\"\" longdesc=\"https:\/\/media.lmneuquen.com\/adjuntos\/195\/imagenes\/004\/121\/0004121163.jpg?0000-00-00-00-00-00\" \/><\/div>\n<\/div>\n<p>Fuente: La Ma\u00f1ana Neuquen<\/p>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Neuquen.-A tres a\u00f1os de la puesta en pr\u00e1ctica, el sistema sigue mejorando.<\/p>\n","protected":false},"author":2,"featured_media":63265,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3357,16],"tags":[],"class_list":["post-63264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-girsu","category-municipales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El reciclaje alcanz\u00f3 el 60% de la basura domiciliaria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El reciclaje alcanz\u00f3 el 60% de la basura domiciliaria\" \/>\n<meta property=\"og:description\" content=\"Neuquen.-A tres a\u00f1os de la puesta en pr\u00e1ctica, el sistema sigue mejorando.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-25T10:00:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/09\/0004120211.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patagonia Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\\\/\"},\"author\":{\"name\":\"Patagonia Ambiental\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\"},\"headline\":\"El reciclaje alcanz\u00f3 el 60% de la basura domiciliaria\",\"datePublished\":\"2019-09-25T10:00:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\\\/\"},\"wordCount\":1012,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/0004120211.jpg\",\"articleSection\":[\"GIRSU\",\"Municipales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\\\/\",\"name\":\"El reciclaje alcanz\u00f3 el 60% de la basura domiciliaria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/0004120211.jpg\",\"datePublished\":\"2019-09-25T10:00:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/0004120211.jpg\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/0004120211.jpg\",\"width\":770,\"height\":435},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El reciclaje alcanz\u00f3 el 60% de la basura domiciliaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\",\"name\":\"Patagonia Ambiental\",\"description\":\"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\",\"https:\\\/\\\/www.facebook.com\\\/share\\\/1C1V8Gv9BX\\\/?mibextid=qi2Omg\",\"@patagoniambiental\",\"https:\\\/\\\/youtube.com\\\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El reciclaje alcanz\u00f3 el 60% de la basura domiciliaria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/","og_locale":"es_ES","og_type":"article","og_title":"El reciclaje alcanz\u00f3 el 60% de la basura domiciliaria","og_description":"Neuquen.-A tres a\u00f1os de la puesta en pr\u00e1ctica, el sistema sigue mejorando.","og_url":"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_author":"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","article_published_time":"2019-09-25T10:00:54+00:00","og_image":[{"width":770,"height":435,"url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/09\/0004120211.jpg","type":"image\/jpeg"}],"author":"Patagonia Ambiental","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/"},"author":{"name":"Patagonia Ambiental","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d"},"headline":"El reciclaje alcanz\u00f3 el 60% de la basura domiciliaria","datePublished":"2019-09-25T10:00:54+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/"},"wordCount":1012,"commentCount":0,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/09\/0004120211.jpg","articleSection":["GIRSU","Municipales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/","url":"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/","name":"El reciclaje alcanz\u00f3 el 60% de la basura domiciliaria","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/09\/0004120211.jpg","datePublished":"2019-09-25T10:00:54+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/#primaryimage","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/09\/0004120211.jpg","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2019\/09\/0004120211.jpg","width":770,"height":435},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/el-reciclaje-alcanzo-el-60-de-la-basura-domiciliaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"El reciclaje alcanz\u00f3 el 60% de la basura domiciliaria"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d","name":"Patagonia Ambiental","description":"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.","sameAs":["http:\/\/www.patagoniambiental.com.ar","https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","@patagoniambiental","https:\/\/youtube.com\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/63264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=63264"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/63264\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media\/63265"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=63264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=63264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=63264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}