{"id":70072,"date":"2020-12-09T07:00:49","date_gmt":"2020-12-09T10:00:49","guid":{"rendered":"http:\/\/patagoniambiental.com.ar\/info\/?p=70072"},"modified":"2020-12-09T09:24:34","modified_gmt":"2020-12-09T12:24:34","slug":"agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/","title":{"rendered":"Agencia Ambiental de R\u00edo Gallegos realiza actividades conjuntas con distintas organizaciones"},"content":{"rendered":"<hgroup class=\"zona-titulo\">\n<h4 class=\"titular\"><strong>R\u00edo Gallegos.-La Agencia Ambiental de la Municipalidad de R\u00edo Gallegos llev\u00f3 a cabo trabajos de limpieza junto a grupos de vecinos. Tambi\u00e9n particip\u00f3 de una capacitaci\u00f3n que fue dictada por profesionales de la Universidad Nacional de la Patagonia Austral.<\/strong><\/h4>\n<\/hgroup>\n<div class=\"row\">\n<div class=\"col-md-1 col-sticky\">\n<div class=\"inner-share-bar cf\">\n<div class=\"item\"><!--more--><\/div>\n<div class=\"item\"><\/div>\n<div class=\"item visible-lg\"><\/div>\n<\/div>\n<\/div>\n<div class=\"col-md-11\">\n<div class=\"main-content-foto\">\n<div class=\"my-gallery main-gallery\" data-pswp-uid=\"1\">\n<figure>\n<div class=\"nfotos\">2 fotos<\/div>\n<p><a href=\"https:\/\/www.eldiarionuevodia.com.ar\/u\/fotografias\/fotosnoticias\/2020\/12\/8\/156713.jpeg\" data-size=\"773x390\"><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.eldiarionuevodia.com.ar\/u\/fotografias\/m\/2020\/12\/8\/f800x450-156713_208159_5050.jpeg\" alt=\"Agencia Ambiental de R\u00edo Gallegos realiza actividades conjuntas con distintas organizaciones\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n<div class=\"fecha-y-seccion\">\n<div class=\"seccion\"><\/div>\n<div class=\"autor f\"><\/div>\n<\/div>\n<div class=\"centrado primer_bnn \"><\/div>\n<div id=\"cuerpo-nota\" class=\"cuerpo-nota\">\n<p>D\u00edas atr\u00e1s, el personal de la Agencia Ambiental Municipal, dependiente de la Direcci\u00f3n de Gesti\u00f3n Ambiental, particip\u00f3 de la jornada de limpieza que se realiz\u00f3 para celebrar el \u00abD\u00eda Mundial del Voluntariado y Cuidado Ambiental\u00bb. La convocatoria la realiz\u00f3 el grupo de vecinos de \u00abQuiero un R\u00edo Gallegos Limpio\u00bb y cont\u00f3 tambi\u00e9n con la participaci\u00f3n de la Asociaci\u00f3n Ambiente Sur. En esta ocasi\u00f3n, se hizo una limpieza profunda de la costanera local, destac\u00e1ndose que esta actividad se hace peri\u00f3dicamente.<\/p>\n<p>En paralelo, tambi\u00e9n se llev\u00f3 adelante una limpieza en la Reserva Natural Urbana \u00abLaguna Mar\u00eda la Gorda\u00bb, con el fin de acompa\u00f1ar el operativo llevado adelante en el Barrio F\u00e1tima por la Secretaria de Obras P\u00fablicas y Urbanismo en conjunto con la Coordinaci\u00f3n de Cenines, dependiente de la Secretar\u00eda de Desarrollo Comunitario.<\/p>\n<p>Por otra parte, se inform\u00f3 que por iniciativa de la Agencia Ambiental Municipal se desarroll\u00f3 una capacitaci\u00f3n para personal de la dependencia sobre Separaci\u00f3n de Residuos y Uso de Herramientas Tecnol\u00f3gicas para trabajar en campo, que estuvo a cargo del ingeniero Daniel Grima y los MG Sabrina Billoni y Ren\u00e9 Asueta, profesionales de la Universidad Nacional de la Patagonia Austral, Unidad Acad\u00e9mica R\u00edo Gallegos (UNPA-UARG).<\/p>\n<p>Consultado al respecto, Grima destac\u00f3 el trabajo realizado porque adem\u00e1s fue \u201cuna capacitaci\u00f3n realizada de manera virtual, v\u00eda Google Meet y en tiempo real, por lo cual fue una experiencia buena\u201d. El ingeniero cont\u00f3 que el eje de la capacitaci\u00f3n fue sobre la problem\u00e1tica de la basura, \u201ccomposici\u00f3n y muestreo de residuos, compostaje, t\u00e9cnicas y legislaci\u00f3n vigente\u201d, entre otros.<\/p>\n<p>Asimismo, se trat\u00f3 de contar aspectos relacionados con \u201cla experiencia de la gesti\u00f3n de residuos a nivel comunitario que se hizo en la UNPA-UARG oportunamente\u201d y de donde se desprenden una serie de puntos muy interesantes sobre el tratamiento de los residuos cuando se hace de manera comunitaria e integral.<\/p>\n<p>Fueron varias clases durante dos semanas, te\u00f3ricas y tambi\u00e9n una pr\u00e1ctica a lo que se le sumar\u00e1n otras el pr\u00f3ximo mes de diciembre, \u201ccon un trabajo final que no ser\u00e1 evaluativo\u201d y donde se enfocar\u00e1n esencialmente en el trabajo de campo.<\/p>\n<p>Cabe se\u00f1alar que la UNPA-UARG hace muchos a\u00f1os que viene trabajando estos aspectos relacionados con el medio ambiente, llev\u00e1ndolos a la comunidad en cuanto las instituciones involucradas as\u00ed lo requieran.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>Fuente:\u00a0https:\/\/www.eldiarionuevodia.com.ar\/locales\/info-general\/2020\/12\/8\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones-131988.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00edo Gallegos.-La Agencia Ambiental de la Municipalidad de R\u00edo Gallegos llev\u00f3 a cabo trabajos de limpieza junto a grupos de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":70073,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3357,16],"tags":[],"class_list":["post-70072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-girsu","category-municipales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Agencia Ambiental de R\u00edo Gallegos realiza actividades conjuntas con distintas organizaciones<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agencia Ambiental de R\u00edo Gallegos realiza actividades conjuntas con distintas organizaciones\" \/>\n<meta property=\"og:description\" content=\"R\u00edo Gallegos.-La Agencia Ambiental de la Municipalidad de R\u00edo Gallegos llev\u00f3 a cabo trabajos de limpieza junto a grupos de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-09T10:00:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-09T12:24:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2020\/12\/f800x450-156713_208159_5050.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"BRAIAN ESTEVEZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\\\/\"},\"author\":{\"name\":\"BRAIAN ESTEVEZ\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/e5af09d700b2e82cb10c6b8800e0c691\"},\"headline\":\"Agencia Ambiental de R\u00edo Gallegos realiza actividades conjuntas con distintas organizaciones\",\"datePublished\":\"2020-12-09T10:00:49+00:00\",\"dateModified\":\"2020-12-09T12:24:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\\\/\"},\"wordCount\":485,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/f800x450-156713_208159_5050.jpeg\",\"articleSection\":[\"GIRSU\",\"Municipales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\\\/\",\"name\":\"Agencia Ambiental de R\u00edo Gallegos realiza actividades conjuntas con distintas organizaciones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/f800x450-156713_208159_5050.jpeg\",\"datePublished\":\"2020-12-09T10:00:49+00:00\",\"dateModified\":\"2020-12-09T12:24:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/f800x450-156713_208159_5050.jpeg\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/f800x450-156713_208159_5050.jpeg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agencia Ambiental de R\u00edo Gallegos realiza actividades conjuntas con distintas organizaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/e5af09d700b2e82cb10c6b8800e0c691\",\"name\":\"BRAIAN ESTEVEZ\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Agencia Ambiental de R\u00edo Gallegos realiza actividades conjuntas con distintas organizaciones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/","og_locale":"es_ES","og_type":"article","og_title":"Agencia Ambiental de R\u00edo Gallegos realiza actividades conjuntas con distintas organizaciones","og_description":"R\u00edo Gallegos.-La Agencia Ambiental de la Municipalidad de R\u00edo Gallegos llev\u00f3 a cabo trabajos de limpieza junto a grupos de [&hellip;]","og_url":"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_published_time":"2020-12-09T10:00:49+00:00","article_modified_time":"2020-12-09T12:24:34+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2020\/12\/f800x450-156713_208159_5050.jpeg","type":"image\/jpeg"}],"author":"BRAIAN ESTEVEZ","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/"},"author":{"name":"BRAIAN ESTEVEZ","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/e5af09d700b2e82cb10c6b8800e0c691"},"headline":"Agencia Ambiental de R\u00edo Gallegos realiza actividades conjuntas con distintas organizaciones","datePublished":"2020-12-09T10:00:49+00:00","dateModified":"2020-12-09T12:24:34+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/"},"wordCount":485,"commentCount":0,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2020\/12\/f800x450-156713_208159_5050.jpeg","articleSection":["GIRSU","Municipales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/","url":"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/","name":"Agencia Ambiental de R\u00edo Gallegos realiza actividades conjuntas con distintas organizaciones","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2020\/12\/f800x450-156713_208159_5050.jpeg","datePublished":"2020-12-09T10:00:49+00:00","dateModified":"2020-12-09T12:24:34+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/#primaryimage","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2020\/12\/f800x450-156713_208159_5050.jpeg","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2020\/12\/f800x450-156713_208159_5050.jpeg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/agencia-ambiental-de-rio-gallegos-realiza-actividades-conjuntas-con-distintas-organizaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"Agencia Ambiental de R\u00edo Gallegos realiza actividades conjuntas con distintas organizaciones"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/e5af09d700b2e82cb10c6b8800e0c691","name":"BRAIAN ESTEVEZ","sameAs":["http:\/\/www.patagoniambiental.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/70072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=70072"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/70072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media\/70073"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=70072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=70072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=70072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}