{"id":7035,"date":"2015-01-13T21:30:57","date_gmt":"2015-01-14T00:30:57","guid":{"rendered":"http:\/\/patagoniambiental.com.ar\/?p=7035"},"modified":"2015-01-13T21:30:57","modified_gmt":"2015-01-14T00:30:57","slug":"argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/","title":{"rendered":"\u00abArgentina podr\u00eda convertirse en un gran exportador de hidr\u00f3geno\u00bb"},"content":{"rendered":"<p>(www.neomundo.com.ar \/ Fuente: Agencia CyTA \u2013 Instituto Leloir. Por Brenda Bertinetti). Un grupo de cient\u00edficos estim\u00f3 que Argentina tiene los recursos necesarios y m\u00e1s que suficientes para producir hidr\u00f3geno a gran escala utilizando fuentes de energ\u00eda renovables. De acuerdo a los especialistas, el pa\u00eds no s\u00f3lo est\u00e1 en condiciones de reemplazar el combustible que importa, sino, adem\u00e1s, de posicionarse de manera ventajosa a nivel global.<\/p>\n<p>\u00abArgentina podr\u00eda constituirse en un gran exportador de hidr\u00f3geno\u00bb, asegura Ramiro Rodr\u00edguez, doctor en f\u00edsica especializado en energ\u00edas sustentables y vectores energ\u00e9ticos de la Universidad Nacional de C\u00f3rdoba (UNC).<\/p>\n<p>\u00abLa posibilidad de producci\u00f3n nacional de hidr\u00f3geno con renovables es semejante a la de Estados Unidos, pero Argentina tiene una superficie tres veces y media menor. Obviamente, esto indica que nuestros recursos son tres veces y medio m\u00e1s abundantes\u00bb, agreg\u00f3.<\/p>\n<p>El hidr\u00f3geno es un gas natural que utilizado como corte de gas natural comprimido (GNC) genera una combusti\u00f3n m\u00e1s limpia, reduciendo los niveles de emisi\u00f3n de di\u00f3xido de carbono al ambiente en 4,5 millones de toneladas anuales. Y seg\u00fan Rodr\u00edguez, el pa\u00eds tiene muchos recursos naturales distribuidos de manera bastante homog\u00e9nea que podr\u00edan servir para producirlo, como las energ\u00edas solar y e\u00f3lica y la biomasa (cultivos o residuos org\u00e1nicos especiales).<\/p>\n<p>En un reciente trabajo en la revista \u00abInternational Journal of Hydrogen Energy\u00bb, Rodr\u00edguez y dos colegas concluyeron que en la Patagonia se pueden producir alrededor de 450 toneladas de hidrogeno anuales por kil\u00f3metro cuadrado aprovechando la energ\u00eda e\u00f3lica de la zona. Si se toma en cuenta su potencial utilizaci\u00f3n como combustible, \u00abel consumo nacional se podr\u00eda abastecer\u00bb, asegur\u00f3 el investigador.<\/p>\n<p>Actualmente, Ram\u00edrez est\u00e1 participando de un trabajo en el que se dise\u00f1an m\u00faltiples proyectos realizables para lograr la sustituci\u00f3n gradual de GNC por mezclas de GNC e hidr\u00f3geno para transporte. Cada proyecto plantea un escenario diferente a largo plazo, basado en la utilizaci\u00f3n de energ\u00eda e\u00f3lica, y al menos dos de ellos podr\u00edan concretarse en el pa\u00eds al cabo de algunas d\u00e9cadas.<\/p>\n<p>En 2010, el pa\u00eds import\u00f3 alrededor de un mill\u00f3n y medio de metros c\u00fabicos de combustible para transporte entre diferentes tipos de gasoil y naftas, seg\u00fan estad\u00edsticas del INDEC. El costo asociado fue de 968 millones de d\u00f3lares. El equivalente energ\u00e9tico es de 486.274 toneladas de hidr\u00f3geno, y los c\u00e1lculos y estimaciones de los investigadores indicaron que el pa\u00eds tiene un potencial de producci\u00f3n de 4.800.000 toneladas anuales a lo largo de su territorio. Explotando tan solo el diez % de las \u00e1reas disponibles, concluyeron, se cubrir\u00eda el combustible importado durante este a\u00f1o.<\/p>\n<p><strong>EL ELEMENTO H<\/strong><\/p>\n<p>El hidr\u00f3geno es un vector de energ\u00eda: es un material capaz de ser utilizado como transportador de energ\u00eda, que cuando llega a destino se lo transforma de manera de obligarlo a liberarla. Adem\u00e1s es una alternativa de energ\u00eda limpia: su proceso de obtenci\u00f3n a partir de fuentes renovables (energ\u00eda solar, vientos, biomasa) no produce contaminaci\u00f3n alguna.<\/p>\n<p>Rodr\u00edguez prev\u00e9 una proyecci\u00f3n formidable para la implementaci\u00f3n de la producci\u00f3n nacional de hidr\u00f3geno. Adem\u00e1s de poseer el mayor potencial off shore del mundo, Argentina cuenta con una de las redes de gasoductos m\u00e1s grande a nivel mundial tambi\u00e9n. Pocos meses atr\u00e1s, la Universidad Nacional de Litoral present\u00f3 el Plan Nacional de Hidr\u00f3geno. El plan tiene estipulado 42 millones de d\u00f3lares como presupuesto para ejecutar 24 programas a corto, mediano y largo plazo.<br \/>\n&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(www.neomundo.com.ar \/ Fuente: Agencia CyTA \u2013 Instituto Leloir. Por Brenda Bertinetti). Un grupo de cient\u00edficos estim\u00f3 que Argentina tiene los [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3277,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[19],"tags":[97,470],"class_list":["post-7035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-hidrogeno","tag-unc"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;Argentina podr\u00eda convertirse en un gran exportador de hidr\u00f3geno&quot;<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Argentina podr\u00eda convertirse en un gran exportador de hidr\u00f3geno&quot;\" \/>\n<meta property=\"og:description\" content=\"(www.neomundo.com.ar \/ Fuente: Agencia CyTA \u2013 Instituto Leloir. Por Brenda Bertinetti). Un grupo de cient\u00edficos estim\u00f3 que Argentina tiene los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-14T00:30:57+00:00\" \/>\n<meta name=\"author\" content=\"Patagonia Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\\\/\"},\"author\":{\"name\":\"Patagonia Ambiental\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\"},\"headline\":\"\u00abArgentina podr\u00eda convertirse en un gran exportador de hidr\u00f3geno\u00bb\",\"datePublished\":\"2015-01-14T00:30:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\\\/\"},\"wordCount\":637,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Hidr\u00f3geno\",\"UNC\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\\\/\",\"name\":\"\\\"Argentina podr\u00eda convertirse en un gran exportador de hidr\u00f3geno\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-01-14T00:30:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abArgentina podr\u00eda convertirse en un gran exportador de hidr\u00f3geno\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\",\"name\":\"Patagonia Ambiental\",\"description\":\"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\",\"https:\\\/\\\/www.facebook.com\\\/share\\\/1C1V8Gv9BX\\\/?mibextid=qi2Omg\",\"@patagoniambiental\",\"https:\\\/\\\/youtube.com\\\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Argentina podr\u00eda convertirse en un gran exportador de hidr\u00f3geno\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/","og_locale":"es_ES","og_type":"article","og_title":"\"Argentina podr\u00eda convertirse en un gran exportador de hidr\u00f3geno\"","og_description":"(www.neomundo.com.ar \/ Fuente: Agencia CyTA \u2013 Instituto Leloir. Por Brenda Bertinetti). Un grupo de cient\u00edficos estim\u00f3 que Argentina tiene los [&hellip;]","og_url":"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_author":"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","article_published_time":"2015-01-14T00:30:57+00:00","author":"Patagonia Ambiental","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/"},"author":{"name":"Patagonia Ambiental","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d"},"headline":"\u00abArgentina podr\u00eda convertirse en un gran exportador de hidr\u00f3geno\u00bb","datePublished":"2015-01-14T00:30:57+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/"},"wordCount":637,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/#primaryimage"},"thumbnailUrl":"","keywords":["Hidr\u00f3geno","UNC"],"articleSection":["Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/","url":"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/","name":"\"Argentina podr\u00eda convertirse en un gran exportador de hidr\u00f3geno\"","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-01-14T00:30:57+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/argentina-podria-convertirse-en-un-gran-exportador-de-hidrogeno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"\u00abArgentina podr\u00eda convertirse en un gran exportador de hidr\u00f3geno\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d","name":"Patagonia Ambiental","description":"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.","sameAs":["http:\/\/www.patagoniambiental.com.ar","https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","@patagoniambiental","https:\/\/youtube.com\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/7035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=7035"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/7035\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=7035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=7035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=7035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}