{"id":73168,"date":"2021-07-01T19:00:00","date_gmt":"2021-07-01T22:00:00","guid":{"rendered":"http:\/\/patagoniambiental.com.ar\/info\/?p=73168"},"modified":"2021-07-01T17:19:30","modified_gmt":"2021-07-01T20:19:30","slug":"la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/","title":{"rendered":"La Pampa: Presentan proyecto para el descarte responsable de medicamentos vencidos"},"content":{"rendered":"\n<!--more-->\n\n\n\n<p>Los diputados provinciales Agustina Garc\u00eda (U.C.R.) y Espartaco Mar\u00edn (FREJUPA) presentaron en conjunto un Proyecto de Ley que propone crear un \u201cPrograma Provincial de Concientizaci\u00f3n y Manejo de Medicamentos Domiciliarios Vencidos, Caducados y\/o en Desuso\u201d. El objetivo es prevenir los riesgos a la salud y el medio ambiente.<\/p>\n\n\n\n<p>Una vez m\u00e1s la tem\u00e1tica ecolog\u00eda une a los j\u00f3venes legisladores. En este caso plantean que las farmacias, instituciones y entidades habilitadas cuenten con al menos un recipiente para que la ciudadan\u00eda deposite all\u00ed los medicamentos vencidos, caducados y\/o en desuso. Es decir, sobrantes de tratamientos espec\u00edficos y preparaciones, en malas condiciones de almacenamiento, con fechas expiradas, envases en mal estado y medicamentos derivados de muestras gratis.<\/p>\n\n\n\n<p>El contenedor llamado \u201cPunto Azul\u201d deber\u00e1 ser instalado en un lugar visible y de f\u00e1cil acceso al p\u00fablico. Adem\u00e1s, ser\u00e1 identificado con carteler\u00eda que indique qu\u00e9 elementos pueden ser depositados all\u00ed. Los medicamentos recibir\u00e1n el tratamiento integral hasta la disposici\u00f3n final o destrucci\u00f3n de los mismos.<\/p>\n\n\n\n<p>\u201cQueremos concientizar y sensibilizar a la ciudadan\u00eda sobre los riesgos para la salud y el medio ambiente que presentan los medicamentos domiciliarios vencidos, caducados y\/o en desuso. Tambi\u00e9n los beneficios de la correcta disposici\u00f3n final en los contenedores instalados para este fin\u201d expres\u00f3 Garc\u00eda.<\/p>\n\n\n\n<p>De aprobarse la Ley, el Poder Ejecutivo designar\u00e1 la Autoridad de Aplicaci\u00f3n al Ministerio de Salud de la Provincia de La Pampa en coordinaci\u00f3n con la Subsecretar\u00eda de Ambiente.<\/p>\n\n\n\n<p>Fuente: https:\/\/www.infopico.com\/2021\/07\/01\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":73169,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3357,59],"tags":[],"class_list":["post-73168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-girsu","category-la-pampa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La Pampa: Presentan proyecto para el descarte responsable de medicamentos vencidos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Pampa: Presentan proyecto para el descarte responsable de medicamentos vencidos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-01T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2021\/07\/medicamentos-vencidos.jpg_118772.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"BRAIAN ESTEVEZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\\\/\"},\"author\":{\"name\":\"BRAIAN ESTEVEZ\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/e5af09d700b2e82cb10c6b8800e0c691\"},\"headline\":\"La Pampa: Presentan proyecto para el descarte responsable de medicamentos vencidos\",\"datePublished\":\"2021-07-01T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\\\/\"},\"wordCount\":279,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/medicamentos-vencidos.jpg_118772.jpg\",\"articleSection\":[\"GIRSU\",\"La Pampa\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\\\/\",\"name\":\"La Pampa: Presentan proyecto para el descarte responsable de medicamentos vencidos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/medicamentos-vencidos.jpg_118772.jpg\",\"datePublished\":\"2021-07-01T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/medicamentos-vencidos.jpg_118772.jpg\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/medicamentos-vencidos.jpg_118772.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Pampa: Presentan proyecto para el descarte responsable de medicamentos vencidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/e5af09d700b2e82cb10c6b8800e0c691\",\"name\":\"BRAIAN ESTEVEZ\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La Pampa: Presentan proyecto para el descarte responsable de medicamentos vencidos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/","og_locale":"es_ES","og_type":"article","og_title":"La Pampa: Presentan proyecto para el descarte responsable de medicamentos vencidos","og_url":"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_published_time":"2021-07-01T22:00:00+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2021\/07\/medicamentos-vencidos.jpg_118772.jpg","type":"image\/jpeg"}],"author":"BRAIAN ESTEVEZ","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/"},"author":{"name":"BRAIAN ESTEVEZ","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/e5af09d700b2e82cb10c6b8800e0c691"},"headline":"La Pampa: Presentan proyecto para el descarte responsable de medicamentos vencidos","datePublished":"2021-07-01T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/"},"wordCount":279,"commentCount":0,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2021\/07\/medicamentos-vencidos.jpg_118772.jpg","articleSection":["GIRSU","La Pampa"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/","url":"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/","name":"La Pampa: Presentan proyecto para el descarte responsable de medicamentos vencidos","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2021\/07\/medicamentos-vencidos.jpg_118772.jpg","datePublished":"2021-07-01T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/#primaryimage","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2021\/07\/medicamentos-vencidos.jpg_118772.jpg","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2021\/07\/medicamentos-vencidos.jpg_118772.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/la-pampa-presentan-proyecto-para-el-descarte-responsable-de-medicamentos-vencidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"La Pampa: Presentan proyecto para el descarte responsable de medicamentos vencidos"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/e5af09d700b2e82cb10c6b8800e0c691","name":"BRAIAN ESTEVEZ","sameAs":["http:\/\/www.patagoniambiental.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/73168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=73168"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/73168\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media\/73169"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=73168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=73168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=73168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}