{"id":79963,"date":"2024-02-22T19:00:00","date_gmt":"2024-02-22T22:00:00","guid":{"rendered":"https:\/\/patagoniambiental.com.ar\/info\/?p=79963"},"modified":"2024-08-14T09:46:27","modified_gmt":"2024-08-14T12:46:27","slug":"la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/","title":{"rendered":"La municipalidad de Ushuaia realiza trabajos en el Paseo del Centenario"},"content":{"rendered":"\n<!--more-->\n\n\n\n<p><strong>USHUAIA.- <\/strong>En conjunto con distintas \u00e1reas de la Municipalidad se llevan adelante tareas de mejoramiento y puesta en valor en distintos puntos de la ciudad de Ushuaia.<\/p>\n\n\n\n<p>Personal de la Subsecretar\u00eda de Servicios P\u00fablicos realiz\u00f3 la limpieza y pintura en las veredas del Paseo del Centenario y el mejoramiento integral del espacio verde estuvo a cargo de la Secretar\u00eda de Medio Ambiente municipal..<\/p>\n\n\n\n<p>Cuadrillas de la Secretar\u00eda de Planificaci\u00f3n e Inversi\u00f3n P\u00fablica continuar\u00e1n con las tareas programadas para el mantenimiento de plazas, paseos y espacios p\u00fablicos, en un trabajo coordinado con la Secretar\u00eda de Medio Ambiente y \u00e1reas asociadas a la tarea de ordenamiento de la ciudad.<\/p>\n\n\n\n<p>Fuente: www.delfuegonoticias.com.ar<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":79964,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[16],"tags":[],"class_list":["post-79963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La municipalidad de Ushuaia realiza trabajos en el Paseo del Centenario<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La municipalidad de Ushuaia realiza trabajos en el Paseo del Centenario\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-22T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-14T12:46:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2024\/02\/45791-la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1423\" \/>\n\t<meta property=\"og:image:height\" content=\"950\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patagonia Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\\\/\"},\"author\":{\"name\":\"Patagonia Ambiental\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\"},\"headline\":\"La municipalidad de Ushuaia realiza trabajos en el Paseo del Centenario\",\"datePublished\":\"2024-02-22T22:00:00+00:00\",\"dateModified\":\"2024-08-14T12:46:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\\\/\"},\"wordCount\":134,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/45791-la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario.jpg\",\"articleSection\":[\"Municipales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\\\/\",\"name\":\"La municipalidad de Ushuaia realiza trabajos en el Paseo del Centenario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/45791-la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario.jpg\",\"datePublished\":\"2024-02-22T22:00:00+00:00\",\"dateModified\":\"2024-08-14T12:46:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/45791-la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario.jpg\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/45791-la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario.jpg\",\"width\":899,\"height\":600,\"caption\":\"Usuhuaia: municipalidad realiza trabajos de puesta en valor del paseo del centenario\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La municipalidad de Ushuaia realiza trabajos en el Paseo del Centenario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\",\"name\":\"Patagonia Ambiental\",\"description\":\"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\",\"https:\\\/\\\/www.facebook.com\\\/share\\\/1C1V8Gv9BX\\\/?mibextid=qi2Omg\",\"@patagoniambiental\",\"https:\\\/\\\/youtube.com\\\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La municipalidad de Ushuaia realiza trabajos en el Paseo del Centenario","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/","og_locale":"es_ES","og_type":"article","og_title":"La municipalidad de Ushuaia realiza trabajos en el Paseo del Centenario","og_url":"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_author":"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","article_published_time":"2024-02-22T22:00:00+00:00","article_modified_time":"2024-08-14T12:46:27+00:00","og_image":[{"width":1423,"height":950,"url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2024\/02\/45791-la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario.jpg","type":"image\/jpeg"}],"author":"Patagonia Ambiental","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/"},"author":{"name":"Patagonia Ambiental","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d"},"headline":"La municipalidad de Ushuaia realiza trabajos en el Paseo del Centenario","datePublished":"2024-02-22T22:00:00+00:00","dateModified":"2024-08-14T12:46:27+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/"},"wordCount":134,"commentCount":0,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2024\/02\/45791-la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario.jpg","articleSection":["Municipales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/","url":"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/","name":"La municipalidad de Ushuaia realiza trabajos en el Paseo del Centenario","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2024\/02\/45791-la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario.jpg","datePublished":"2024-02-22T22:00:00+00:00","dateModified":"2024-08-14T12:46:27+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/#primaryimage","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2024\/02\/45791-la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario.jpg","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2024\/02\/45791-la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario.jpg","width":899,"height":600,"caption":"Usuhuaia: municipalidad realiza trabajos de puesta en valor del paseo del centenario"},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/la-municipalidad-realiza-trabajos-de-puesta-en-valor-del-paseo-del-centenario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"La municipalidad de Ushuaia realiza trabajos en el Paseo del Centenario"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d","name":"Patagonia Ambiental","description":"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.","sameAs":["http:\/\/www.patagoniambiental.com.ar","https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","@patagoniambiental","https:\/\/youtube.com\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/79963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=79963"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/79963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media\/79964"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=79963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=79963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=79963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}