{"id":81789,"date":"2024-05-07T07:00:00","date_gmt":"2024-05-07T10:00:00","guid":{"rendered":"https:\/\/patagoniambiental.com.ar\/info\/?p=81789"},"modified":"2024-08-12T11:26:06","modified_gmt":"2024-08-12T14:26:06","slug":"4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/","title":{"rendered":"4 cosas que pod\u00e9s hacer para proteger a las plantas de una plaga en oto\u00f1o"},"content":{"rendered":"\n<!--more-->\n\n\n\n<p><strong>Si quer\u00e9s que tu jard\u00edn luzca precioso sin importar el cambio de clima, segu\u00ed estos consejos.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.minutoneuquen.com\/u\/fotografias\/fotosnoticias\/2024\/4\/26\/666111.jpg\"><img decoding=\"async\" src=\"https:\/\/www.minutoneuquen.com\/u\/fotografias\/m\/2024\/4\/26\/f685x385-666111_703804_477.jpg\" alt=\"4 cosas que pod\u00e9s hacer para proteger a las plantas de la plaga que las persigue en oto\u00f1o\"\/><\/a><figcaption class=\"wp-element-caption\">Plantas. Fuente: (Instagram).<\/figcaption><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.minutoneuquen.com\/autor\/leila-perez.html\">Por\u00a0Leila P\u00e9rez<\/a>.-Cuando cambian las estaciones clim\u00e1ticas, las necesidades b\u00e1sicas en el cuidado de nuestras\u00a0<strong>plantas\u00a0<\/strong>tambi\u00e9n hacen lo suyo y, por ello, vamos a ahondar en cuatro consejos de expertos en jardiner\u00eda que son f\u00e1ciles de realizar.<\/p>\n\n\n\n<p>En Minuto Neuqu\u00e9n buscamos encontrar&nbsp;la soluci\u00f3n a los problemas que puedan presentarse en tus&nbsp;<a href=\"https:\/\/www.minutoneuquen.com\/entretenimiento\/2024\/4\/27\/la-forma-mas-efectiva-para-proteger-las-suculentas-en-temporada-de-lluvia-347991.html\">ejemplares<\/a>&nbsp;y por ello&nbsp;te daremos cuatro estrategias que son&nbsp;muy efectivas para que tus<strong>&nbsp;plantas&nbsp;<\/strong>puedan crecer sin inconvenientes por plagas.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.minutoneuquen.com\/u\/fotografias\/m\/2022\/3\/21\/f768x1-534790_534917_5050.jpg\" alt=\"\"\/><figcaption class=\"wp-element-caption\">Plantas y \u00e1rboles pueden verse afectados por la presencia de hongos o plagas que deterioren su salud.<\/figcaption><\/figure>\n\n\n\n<p>La temporada oto\u00f1al puede&nbsp;favorecer la proliferaci\u00f3n de hongos en las hojas de nuestras<strong>&nbsp;plantas<\/strong>. Por ello, es crucial implementar estrategias preventivas. A continuaci\u00f3n, te brindamos los consejos que los mejores en el mundo de&nbsp;<a href=\"https:\/\/www.minutoneuquen.com\/temas\/plantas-17343.html\">la bot\u00e1nica<\/a>&nbsp;aportan para hacer de tu jard\u00edn un espacio mejor.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-un-desafio-dificil-de-desaprovechar\">Un desaf\u00edo dif\u00edcil de desaprovechar<\/h2>\n\n\n\n<p>Una de las primeras medidas es la eliminaci\u00f3n meticulosa de hojas ca\u00eddas y cualquier planta que muestre tener signos de enfermedad o est\u00e9 en estado de descomposici\u00f3n. Esto ayudar\u00e1 a reducir la propagaci\u00f3n de pat\u00f3genos que podr\u00edan afectar el follaje sano de tus especies.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.minutoneuquen.com\/u\/fotografias\/m\/2024\/3\/6\/f768x1-651135_651262_2353.jpg\" alt=\"\"\/><figcaption class=\"wp-element-caption\">Con estos trucos, se puede reducir significativamente la incidencia de hongos en las hojas durante la temporada oto\u00f1al.<\/figcaption><\/figure>\n\n\n\n<p>Otro punto clave a tener en cuenta&nbsp;es asegurar que las&nbsp;<strong>plantas<\/strong>&nbsp;tengan suficiente espacio entre s\u00ed, ya que el hacinamiento puede crear un ambiente ideal para el desarrollo de hongos al limitarse la circulaci\u00f3n de aire y aumentar la humedad alrededor de las hojas.&nbsp;<\/p>\n\n\n\n<p>El manejo del riego tambi\u00e9n juega un papel fundamental en la prevenci\u00f3n de hongos en oto\u00f1o. Es menester evitar el riego excesivo. El agua estancada en el suelo y sobre las hojas puede crear un ambiente h\u00famedo que favorece el crecimiento de hongos.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.minutoneuquen.com\/u\/fotografias\/m\/2024\/4\/20\/f768x1-664118_664245_5050.jpg\" alt=\"\"\/><figcaption class=\"wp-element-caption\">Controlar el riego para mantener el suelo ligeramente h\u00famedo, pero no saturado, es clave.<\/figcaption><\/figure>\n\n\n\n<p>Otro tip para tener en consideraci\u00f3n es el de aplicar una capa de mulch org\u00e1nico alrededor de las plantas, debido a que este ayuda a retener la humedad en el suelo, reduce la erosi\u00f3n&nbsp;y act\u00faa como una barrera protectora que evita que las gotas de lluvia salpiquen directamente sobre las hojas, disminuyendo as\u00ed el riesgo de infecciones.<\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/www.minutoneuquen.com\/entretenimiento\/2024\/4\/27\/cosas-que-podes-hacer-para-proteger-las-plantas-de-la-plaga-que-las-persigue-en-otono-348004.html\">www.minutoneuquen.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":81790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[16],"tags":[],"class_list":["post-81789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>4 cosas que pod\u00e9s hacer para proteger a las plantas de una plaga en oto\u00f1o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 cosas que pod\u00e9s hacer para proteger a las plantas de una plaga en oto\u00f1o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-07T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-12T14:26:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2024\/04\/Sin-titulo-25.png\" \/>\n\t<meta property=\"og:image:width\" content=\"833\" \/>\n\t<meta property=\"og:image:height\" content=\"513\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Patagonia Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\\\/\"},\"author\":{\"name\":\"Patagonia Ambiental\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\"},\"headline\":\"4 cosas que pod\u00e9s hacer para proteger a las plantas de una plaga en oto\u00f1o\",\"datePublished\":\"2024-05-07T10:00:00+00:00\",\"dateModified\":\"2024-08-12T14:26:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\\\/\"},\"wordCount\":456,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Sin-titulo-25.png\",\"articleSection\":[\"Municipales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\\\/\",\"name\":\"4 cosas que pod\u00e9s hacer para proteger a las plantas de una plaga en oto\u00f1o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Sin-titulo-25.png\",\"datePublished\":\"2024-05-07T10:00:00+00:00\",\"dateModified\":\"2024-08-12T14:26:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\\\/#primaryimage\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Sin-titulo-25.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Sin-titulo-25.png\",\"width\":833,\"height\":513},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4 cosas que pod\u00e9s hacer para proteger a las plantas de una plaga en oto\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\",\"name\":\"Patagonia Ambiental\",\"description\":\"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\",\"https:\\\/\\\/www.facebook.com\\\/share\\\/1C1V8Gv9BX\\\/?mibextid=qi2Omg\",\"@patagoniambiental\",\"https:\\\/\\\/youtube.com\\\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"4 cosas que pod\u00e9s hacer para proteger a las plantas de una plaga en oto\u00f1o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/","og_locale":"es_ES","og_type":"article","og_title":"4 cosas que pod\u00e9s hacer para proteger a las plantas de una plaga en oto\u00f1o","og_url":"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_author":"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","article_published_time":"2024-05-07T10:00:00+00:00","article_modified_time":"2024-08-12T14:26:06+00:00","og_image":[{"width":833,"height":513,"url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2024\/04\/Sin-titulo-25.png","type":"image\/png"}],"author":"Patagonia Ambiental","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/"},"author":{"name":"Patagonia Ambiental","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d"},"headline":"4 cosas que pod\u00e9s hacer para proteger a las plantas de una plaga en oto\u00f1o","datePublished":"2024-05-07T10:00:00+00:00","dateModified":"2024-08-12T14:26:06+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/"},"wordCount":456,"commentCount":0,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2024\/04\/Sin-titulo-25.png","articleSection":["Municipales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/","url":"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/","name":"4 cosas que pod\u00e9s hacer para proteger a las plantas de una plaga en oto\u00f1o","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/#primaryimage"},"thumbnailUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2024\/04\/Sin-titulo-25.png","datePublished":"2024-05-07T10:00:00+00:00","dateModified":"2024-08-12T14:26:06+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/#primaryimage","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2024\/04\/Sin-titulo-25.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2024\/04\/Sin-titulo-25.png","width":833,"height":513},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/4-cosas-que-podes-hacer-para-proteger-a-las-plantas-de-la-plaga-que-las-persigue-en-otono\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"4 cosas que pod\u00e9s hacer para proteger a las plantas de una plaga en oto\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d","name":"Patagonia Ambiental","description":"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.","sameAs":["http:\/\/www.patagoniambiental.com.ar","https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","@patagoniambiental","https:\/\/youtube.com\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/81789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=81789"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/81789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media\/81790"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=81789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=81789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=81789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}