{"id":8650,"date":"2015-02-26T09:00:55","date_gmt":"2015-02-26T12:00:55","guid":{"rendered":"http:\/\/patagoniambiental.com.ar\/?p=8650"},"modified":"2015-02-26T09:00:55","modified_gmt":"2015-02-26T12:00:55","slug":"gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/","title":{"rendered":"Gobierno proveer\u00e1 energ\u00eda el\u00e9ctrica a 4000 terrenos en Andorra"},"content":{"rendered":"<p style=\"text-align: justify;\">Ushuaia &#8211; El Gobierno de la Provincia a trav\u00e9s de la Direcci\u00f3n Provincial de Energ\u00eda, avanza en la gesti\u00f3n de la obra de Red Troncal y construcci\u00f3n de un centro de distribuci\u00f3n de energ\u00eda el\u00e9ctrica en el Barrio Valle de Andorra, que proveer\u00e1 del servicio a unos 4000 terrenos.<!--more--><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">El Presidente de la DPE, Juan Carlos Saldivia, expres\u00f3 que dicha obra fue licitada en el pasado mes de octubre y las empresas ganadoras de la licitaci\u00f3n ya se encuentran en proceso de firmar los contratos de adjudicaci\u00f3n correspondientes, lo que motivar\u00e1 la pronta puesta en marcha de las obras.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En el mismo sentido Saldivia afirm\u00f3 que \u201ces una obra realmente importante ya que, adem\u00e1s de favorecer a los residenciales, afectar\u00e1 a toda la infraestructura gubernamental como municipal del sector\u201d, asegurando que \u201cpara muchos usuarios de Andorra no ten\u00edamos la potencia de energ\u00eda, as\u00ed que esto viene a solucionar ese punto y esperamos poder acortar los plazos de obra para que todos los usuarios de la zona puedan comenzar adherirse lo antes posible\u201d.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">La obra distribuir\u00e1 33\/13,2 KV, y tiene un presupuesto oficial de $56.487.020,36 que ser\u00e1 financiado mediante el Fideicomiso Austral, con un plazo de ejecuci\u00f3n de 10 meses.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Saldivia inform\u00f3 adem\u00e1s, que en el marco del Convenio de Convergencia El\u00e9ctrica, se estar\u00e1n realizando prontamente las licitaciones de l\u00ednea de baja tensi\u00f3n para todos los usuarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ushuaia &#8211; El Gobierno de la Provincia a trav\u00e9s de la Direcci\u00f3n Provincial de Energ\u00eda, avanza en la gesti\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8651,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[25],"tags":[2713,353,2714],"class_list":["post-8650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tierra-del-fuego","tag-andorra","tag-energia-electrica","tag-red-troncal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gobierno proveer\u00e1 energ\u00eda el\u00e9ctrica a 4000 terrenos en Andorra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno proveer\u00e1 energ\u00eda el\u00e9ctrica a 4000 terrenos en Andorra\" \/>\n<meta property=\"og:description\" content=\"Ushuaia &#8211; El Gobierno de la Provincia a trav\u00e9s de la Direcci\u00f3n Provincial de Energ\u00eda, avanza en la gesti\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-26T12:00:55+00:00\" \/>\n<meta name=\"author\" content=\"Patagonia Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\\\/\"},\"author\":{\"name\":\"Patagonia Ambiental\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\"},\"headline\":\"Gobierno proveer\u00e1 energ\u00eda el\u00e9ctrica a 4000 terrenos en Andorra\",\"datePublished\":\"2015-02-26T12:00:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\\\/\"},\"wordCount\":251,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"andorra\",\"energ\u00eda el\u00e9ctrica\",\"red troncal\"],\"articleSection\":[\"Tierra del Fuego\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\\\/\",\"name\":\"Gobierno proveer\u00e1 energ\u00eda el\u00e9ctrica a 4000 terrenos en Andorra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-02-26T12:00:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno proveer\u00e1 energ\u00eda el\u00e9ctrica a 4000 terrenos en Andorra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\",\"name\":\"Patagonia Ambiental\",\"description\":\"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\",\"https:\\\/\\\/www.facebook.com\\\/share\\\/1C1V8Gv9BX\\\/?mibextid=qi2Omg\",\"@patagoniambiental\",\"https:\\\/\\\/youtube.com\\\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gobierno proveer\u00e1 energ\u00eda el\u00e9ctrica a 4000 terrenos en Andorra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno proveer\u00e1 energ\u00eda el\u00e9ctrica a 4000 terrenos en Andorra","og_description":"Ushuaia &#8211; El Gobierno de la Provincia a trav\u00e9s de la Direcci\u00f3n Provincial de Energ\u00eda, avanza en la gesti\u00f3n de [&hellip;]","og_url":"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_author":"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","article_published_time":"2015-02-26T12:00:55+00:00","author":"Patagonia Ambiental","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/"},"author":{"name":"Patagonia Ambiental","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d"},"headline":"Gobierno proveer\u00e1 energ\u00eda el\u00e9ctrica a 4000 terrenos en Andorra","datePublished":"2015-02-26T12:00:55+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/"},"wordCount":251,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/#primaryimage"},"thumbnailUrl":"","keywords":["andorra","energ\u00eda el\u00e9ctrica","red troncal"],"articleSection":["Tierra del Fuego"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/","url":"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/","name":"Gobierno proveer\u00e1 energ\u00eda el\u00e9ctrica a 4000 terrenos en Andorra","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-02-26T12:00:55+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/gobierno-proveera-energia-electrica-a-4000-terrenos-en-andorra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"Gobierno proveer\u00e1 energ\u00eda el\u00e9ctrica a 4000 terrenos en Andorra"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d","name":"Patagonia Ambiental","description":"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.","sameAs":["http:\/\/www.patagoniambiental.com.ar","https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","@patagoniambiental","https:\/\/youtube.com\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/8650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=8650"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/8650\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=8650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=8650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=8650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}