{"id":9138,"date":"2015-03-10T09:00:45","date_gmt":"2015-03-10T12:00:45","guid":{"rendered":"http:\/\/patagoniambiental.com.ar\/?p=9138"},"modified":"2015-03-10T09:00:45","modified_gmt":"2015-03-10T12:00:45","slug":"el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/","title":{"rendered":"El Salado ya no llega hasta la reforma: un r\u00edo en v\u00edas de desaparici\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\">Santa Rosa &#8211; El r\u00edo que otrora atravesaba de norte a sur el territorio pampeano, ya casi no existe. El magro caudal que ingresa a la provincia se extingue unos kil\u00f3metros al sur del puente sobre la ruta 10. \u00bfUn destino similar al Atuel?<!--more--><\/p>\n<p style=\"text-align: justify;\">Tal como denunci\u00f3 la semana pasada la Fundaci\u00f3n Chadileuv\u00fa, el r\u00edo Salado &#8211; Chadileuv\u00fa est\u00e1 en camino de correr la misma suerte que el Atuel: desaparecer del territorio pampeano. Algo de eso ya est\u00e1 ocurriendo. El peque\u00f1o caudal que ingresa a nuestra provincia apenas mantiene el cauce en actividad hasta unos kil\u00f3metros al sur del l\u00edmite con las provincias de Mendoza y San Luis, por donde ingresa a La Pampa. Su peque\u00f1o escurrimiento le permite llegar hasta el puente sobre la ruta provincial 10 y unos kil\u00f3metros aguas abajo ya desaparece.<\/p>\n<p style=\"text-align: justify;\">Ayer, un vecino que viaj\u00f3 al oeste por la ruta provincial 20, la llamada \u00abConquista del Desierto\u00bb, par\u00f3 en el puente de la localidad de La Reforma y fotografi\u00f3 la situaci\u00f3n actual del r\u00edo que hasta no hace mucho cruzaba en sentido norte-sur gran parte del territorio pampeano. Se puede ver el cauce seco, totalmente salinizado, y solo algunas charcos aislados. No hay se\u00f1ales de un escurrimiento de importancia en el \u00faltimo tiempo.<\/p>\n<p style=\"text-align: justify;\">La imagen que sintetiza el estado del r\u00edo se puede ver a pocos metros del puente 20: la escala limnim\u00e9trica rodeada por palos y piedras, sin nivel de agua que medir. Esta escala permite una lectura r\u00e1pida del escurrimiento&#8230; cuando lo hay. Cuando ello ocurre, la altura que alcanza el r\u00edo es proporcional al caudal que escurre en ese momento. Una simple f\u00f3rmula permite convertir esos cent\u00edmetros en metros c\u00fabicos por segundo.<\/p>\n<p style=\"text-align: justify;\"><strong>M\u00e1s represas<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">La lenta desaparici\u00f3n del Salado &#8211; Chadileuv\u00fa es consecuencia de una serie de represas que se est\u00e1n haciendo a muchos kil\u00f3metros de nuestra provincia, en su mayor\u00eda en la provincia de San Juan. En esa provincia se encuentra el r\u00edo San Juan, que es el m\u00e1s caudaloso de la cuenca h\u00eddrica del Desaguadero &#8211; Salado &#8211; Chadileuv\u00fa. A la represa de Ull\u00fan -inaugurada hace m\u00e1s de tres d\u00e9cadas- se le sum\u00f3 hace unos a\u00f1os el dique de Caracoles, cuyo embalse est\u00e1 en v\u00edas de llenado. Esta acci\u00f3n ser\u00eda la principal causante de la agon\u00eda saladina en territorio pampeano.<\/p>\n<p style=\"text-align: justify;\">El panorama se agravar\u00e1 en poco tiempo cuando se termine de construir la represa de Punta Negra, tambi\u00e9n sobre el San Juan, y m\u00e1s a\u00fan cuando se encare El Tambolar, otro embalse previsto sobre este curso.<\/p>\n<p style=\"text-align: justify;\">Junto con estas obras de infraestructura, el aprovechamiento que se hace de este r\u00edo y otros que integran la cuenca, el hecho de tratarse de un sistema h\u00eddrico que atraviesa zonas des\u00e9rticas o semides\u00e9rticas, ser cursos de agua de mediana magnitud, y la ausencia de un comit\u00e9 de cuenca u \u00f3rgano que administre los usos en forma equitativa para el beneficio de todas las provincias, confluyen en el resultado por hoy por hoy ofrece el r\u00edo en territorio pampeano.<\/p>\n<p style=\"text-align: justify;\">FUENTE: laarena.com.ar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santa Rosa &#8211; El r\u00edo que otrora atravesaba de norte a sur el territorio pampeano, ya casi no existe. El [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9141,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[53],"tags":[1089,1178,1417,2902],"class_list":["post-9138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-atuel","tag-la-pampa","tag-mendoza","tag-salado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El Salado ya no llega hasta la reforma: un r\u00edo en v\u00edas de desaparici\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Salado ya no llega hasta la reforma: un r\u00edo en v\u00edas de desaparici\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Santa Rosa &#8211; El r\u00edo que otrora atravesaba de norte a sur el territorio pampeano, ya casi no existe. El [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-10T12:00:45+00:00\" \/>\n<meta name=\"author\" content=\"Patagonia Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\\\/\"},\"author\":{\"name\":\"Patagonia Ambiental\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\"},\"headline\":\"El Salado ya no llega hasta la reforma: un r\u00edo en v\u00edas de desaparici\u00f3n\",\"datePublished\":\"2015-03-10T12:00:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\\\/\"},\"wordCount\":555,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Atuel\",\"La Pampa\",\"mendoza\",\"salado\"],\"articleSection\":[\"General\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\\\/\",\"name\":\"El Salado ya no llega hasta la reforma: un r\u00edo en v\u00edas de desaparici\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-03-10T12:00:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Salado ya no llega hasta la reforma: un r\u00edo en v\u00edas de desaparici\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\",\"name\":\"Patagonia Ambiental\",\"description\":\"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\",\"https:\\\/\\\/www.facebook.com\\\/share\\\/1C1V8Gv9BX\\\/?mibextid=qi2Omg\",\"@patagoniambiental\",\"https:\\\/\\\/youtube.com\\\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El Salado ya no llega hasta la reforma: un r\u00edo en v\u00edas de desaparici\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/","og_locale":"es_ES","og_type":"article","og_title":"El Salado ya no llega hasta la reforma: un r\u00edo en v\u00edas de desaparici\u00f3n","og_description":"Santa Rosa &#8211; El r\u00edo que otrora atravesaba de norte a sur el territorio pampeano, ya casi no existe. El [&hellip;]","og_url":"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_author":"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","article_published_time":"2015-03-10T12:00:45+00:00","author":"Patagonia Ambiental","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/"},"author":{"name":"Patagonia Ambiental","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d"},"headline":"El Salado ya no llega hasta la reforma: un r\u00edo en v\u00edas de desaparici\u00f3n","datePublished":"2015-03-10T12:00:45+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/"},"wordCount":555,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/#primaryimage"},"thumbnailUrl":"","keywords":["Atuel","La Pampa","mendoza","salado"],"articleSection":["General"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/","url":"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/","name":"El Salado ya no llega hasta la reforma: un r\u00edo en v\u00edas de desaparici\u00f3n","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-03-10T12:00:45+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/el-salado-ya-no-llega-hasta-la-reforma-un-rio-en-vias-de-desaparicion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"El Salado ya no llega hasta la reforma: un r\u00edo en v\u00edas de desaparici\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d","name":"Patagonia Ambiental","description":"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.","sameAs":["http:\/\/www.patagoniambiental.com.ar","https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","@patagoniambiental","https:\/\/youtube.com\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/9138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=9138"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/9138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=9138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=9138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=9138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}