{"id":9167,"date":"2015-03-10T19:00:32","date_gmt":"2015-03-10T22:00:32","guid":{"rendered":"http:\/\/patagoniambiental.com.ar\/?p=9167"},"modified":"2015-03-10T19:00:32","modified_gmt":"2015-03-10T22:00:32","slug":"avanza-la-comision-nacional-de-energia-atomica","status":"publish","type":"post","link":"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/","title":{"rendered":"Avanza la Comisi\u00f3n Nacional de Energ\u00eda At\u00f3mica  \u00a0"},"content":{"rendered":"<p style=\"text-align: justify;\">Buenos Aires &#8211; El gobierno del ex presidente N\u00e9stor Kirchner volvi\u00f3 a otorgarle centralidad a la tecnolog\u00eda nuclear como componente estrat\u00e9gico de la reindustrializaci\u00f3n del pa\u00eds. En 2006 puso en marcha el Plan Nuclear Argentino. El pa\u00eds se perfila como uno de los l\u00edderes mundiales en el segmento de reactores de generaci\u00f3n el\u00e9ctrica de media y baja potencia.<!--more--><\/p>\n<p style=\"text-align: justify;\">El desarrollo de la energ\u00eda nuclear en nuestro pa\u00eds tiene sus or\u00edgenes en el peronismo. Hace ya m\u00e1s de 60 a\u00f1os se creaba la Comisi\u00f3n Nacional de Energ\u00eda At\u00f3mica (CNEA), una entidad dedicada al estudio cient\u00edfico, desarrollo y aplicaci\u00f3n de la energ\u00eda nuclear con fines pac\u00edficos. El gobierno de Juan Domingo Per\u00f3n invirti\u00f3 en el sector nuclear y puso en el horizonte la b\u00fasqueda de la autonom\u00eda tecnol\u00f3gica.<\/p>\n<p style=\"text-align: justify;\">A partir de all\u00ed se inici\u00f3 un largo camino. Se consolidaron las actividades para la construcci\u00f3n y operaci\u00f3n de reactores de investigaci\u00f3n y sus combustibles, la producci\u00f3n de radiois\u00f3topos y el empleo de las radiaciones para diagn\u00f3stico y tratamiento m\u00e9dico. As\u00ed se lleg\u00f3 a producir, con solo dos centrales (Atucha I y Embalse) el 8% de la energ\u00eda el\u00e9ctrica del pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">La CNEA tuvo que resistir a los avatares de las pol\u00edticas neoliberales en los a\u00f1os noventa, ya que sufri\u00f3 durante el menemismo la reducci\u00f3n de su presupuesto, los retiros voluntarios y el desaliento al desarrollo de la industria nuclear. Pero en el a\u00f1o 2006 el gobierno del ex presidente N\u00e9stor Kirchner volvi\u00f3 a otorgarle centralidad para el desarrollo y la reindustrializaci\u00f3n del pa\u00eds al \u00e1rea nuclear y lanz\u00f3 el Plan Nuclear Argentino.<\/p>\n<p style=\"text-align: justify;\">Este fue un momento refundacional en la historia de la CNEA. Se estableci\u00f3 un programa para la consolidaci\u00f3n de la energ\u00eda nuclear no s\u00f3lo como fuente de generaci\u00f3n el\u00e9ctrica sino tambi\u00e9n para la ampliaci\u00f3n del desarrollo de las aplicaciones de la tecnolog\u00eda nuclear en la salud p\u00fablica (medicina nuclear y radioterapia), el agro y la industria.<\/p>\n<p style=\"text-align: justify;\">Con este nuevo impulso del gobierno nacional se reactiv\u00f3 la finalizaci\u00f3n de obras civiles y montajes electromec\u00e1nicos de la Central Nuclear \u00abPresidente N\u00e9stor C. Kirchner\u00bb (Atucha II), que estuvo paralizada entre 1994-2006, y es la tercera planta de generaci\u00f3n nucleoel\u00e9ctrica del pa\u00eds. En febrero de este a\u00f1o logr\u00f3 producir a su m\u00e1xima potencia con una generaci\u00f3n de 745 megavatios (MV).<\/p>\n<p style=\"text-align: justify;\">Otros proyectos que se destacan son la extensi\u00f3n de vida de la Central Nuclear Embalse para que pueda operar por 30 a\u00f1os adicionales y el CAREM 25 (Central Argentina de Elementos Modulares) proyecto iniciado en el a\u00f1o 2014 para la construcci\u00f3n de la primera central nuclear de potencia (25 MW), desarrollada \u00edntegramente en Argentina. Se espera que al menos el 70% de sus insumos, componentes y servicios vinculados sea provisto por empresas nacionales. Con ello el pa\u00eds se perfilar\u00eda como uno de los l\u00edderes mundiales en el segmento de reactores de generaci\u00f3n el\u00e9ctrica de media y baja potencia.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n son muy importantes los avances respecto al enriquecimiento de uranio con fines pac\u00edficos. El Complejo Tecnol\u00f3gico Pilcaniyeu es una planta piloto que ya trabaj\u00f3 en la d\u00e9cada del ochenta, fue pr\u00e1cticamente desmantelada en los a\u00f1os &#8217;90 y por decisi\u00f3n pol\u00edtica se puso en marcha nuevamente en la d\u00e9cada \u00faltima. Desde 2007 Pilcaniyeu recibi\u00f3 inversiones por cerca de 120 millones de pesos y fue reinaugurada en 2010. Poseer esta tecnolog\u00eda permite que nuestro pa\u00eds pueda proveer \u2013en forma independiente y soberana\u2013 combustible nuclear tanto para abastecer a reactores argentinos como para exportar al mundo.<\/p>\n<p style=\"text-align: justify;\">Es oportuno destacar que actualmente nuestro pa\u00eds est\u00e1 ubicado entre los nueve de mayor desarrollo nuclear y que es l\u00edder en Am\u00e9rica Latina, ya que produce, se autoabastece y exporta en el mercado de la energ\u00eda nuclear.<\/p>\n<p style=\"text-align: justify;\">En este marco y con la perspectiva de los desaf\u00edos en materia de energ\u00eda nuclear para los pr\u00f3ximos a\u00f1os, el gobierno Cristina Fern\u00e1ndez de Kirchner puso en marcha un proyecto para la construcci\u00f3n de una cuarta central nuclear, denominada \u00abProyecto Nacional\u00bb.<\/p>\n<p style=\"text-align: justify;\">Para ello se firm\u00f3 un acuerdo de cooperaci\u00f3n con el gobierno de la Rep\u00fablica Popular China con el objetivo de contribuir al desarrollo de un reactor de tubos de presi\u00f3n y agua pesada de 800 MW, que supera la potencia del resto de las centrales nucleares argentinas. El plazo de construcci\u00f3n se estima en ocho a\u00f1os. Tambi\u00e9n se espera la construcci\u00f3n de una quinta central, de unos 1000 MW, aunque reci\u00e9n est\u00e1 en la etapa de desarrollo.<\/p>\n<p style=\"text-align: justify;\">La Argentina es uno de los pocos pa\u00edses que ha alcanzado un considerable avance la industria nuclear en los \u00faltimos a\u00f1os. Sin duda, la CNEA ha sido clave para el desarrollo cient\u00edfico y tecnol\u00f3gico en el \u00e1rea.<\/p>\n<p style=\"text-align: justify;\">FUENTE: Tiempo Argentino<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenos Aires &#8211; El gobierno del ex presidente N\u00e9stor Kirchner volvi\u00f3 a otorgarle centralidad a la tecnolog\u00eda nuclear como componente [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9168,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[19],"tags":[131,1577,2911],"class_list":["post-9167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-cnea","tag-kirchner","tag-reindustrializacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Avanza la Comisi\u00f3n Nacional de Energ\u00eda At\u00f3mica \u00a0<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avanza la Comisi\u00f3n Nacional de Energ\u00eda At\u00f3mica \u00a0\" \/>\n<meta property=\"og:description\" content=\"Buenos Aires &#8211; El gobierno del ex presidente N\u00e9stor Kirchner volvi\u00f3 a otorgarle centralidad a la tecnolog\u00eda nuclear como componente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/patagonia.ambiental\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-10T22:00:32+00:00\" \/>\n<meta name=\"author\" content=\"Patagonia Ambiental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PatAmb\" \/>\n<meta name=\"twitter:site\" content=\"@PatAmb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/avanza-la-comision-nacional-de-energia-atomica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/avanza-la-comision-nacional-de-energia-atomica\\\/\"},\"author\":{\"name\":\"Patagonia Ambiental\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\"},\"headline\":\"Avanza la Comisi\u00f3n Nacional de Energ\u00eda At\u00f3mica \u00a0\",\"datePublished\":\"2015-03-10T22:00:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/avanza-la-comision-nacional-de-energia-atomica\\\/\"},\"wordCount\":858,\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/avanza-la-comision-nacional-de-energia-atomica\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"CNEA\",\"Kirchner\",\"reindustrializaci\u00f3n\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/avanza-la-comision-nacional-de-energia-atomica\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/avanza-la-comision-nacional-de-energia-atomica\\\/\",\"name\":\"Avanza la Comisi\u00f3n Nacional de Energ\u00eda At\u00f3mica \u00a0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/avanza-la-comision-nacional-de-energia-atomica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/avanza-la-comision-nacional-de-energia-atomica\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-03-10T22:00:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/avanza-la-comision-nacional-de-energia-atomica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/avanza-la-comision-nacional-de-energia-atomica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/avanza-la-comision-nacional-de-energia-atomica\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/avanza-la-comision-nacional-de-energia-atomica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avanza la Comisi\u00f3n Nacional de Energ\u00eda At\u00f3mica \u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#website\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"name\":\"Patagonia Ambiental\",\"description\":\"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia\",\"publisher\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#organization\",\"name\":\"Patagonia Ambiental\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"contentUrl\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/LOGO-PATAGONIA-AMBIENTAL.png\",\"width\":433,\"height\":250,\"caption\":\"Patagonia Ambiental\"},\"image\":{\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/patagonia.ambiental\",\"https:\\\/\\\/x.com\\\/PatAmb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/patagoniambiental.com.ar\\\/info\\\/#\\\/schema\\\/person\\\/db12bff64bbcbf6a253710bf0ea37b5d\",\"name\":\"Patagonia Ambiental\",\"description\":\"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.\",\"sameAs\":[\"http:\\\/\\\/www.patagoniambiental.com.ar\",\"https:\\\/\\\/www.facebook.com\\\/share\\\/1C1V8Gv9BX\\\/?mibextid=qi2Omg\",\"@patagoniambiental\",\"https:\\\/\\\/youtube.com\\\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Avanza la Comisi\u00f3n Nacional de Energ\u00eda At\u00f3mica \u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/","og_locale":"es_ES","og_type":"article","og_title":"Avanza la Comisi\u00f3n Nacional de Energ\u00eda At\u00f3mica \u00a0","og_description":"Buenos Aires &#8211; El gobierno del ex presidente N\u00e9stor Kirchner volvi\u00f3 a otorgarle centralidad a la tecnolog\u00eda nuclear como componente [&hellip;]","og_url":"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/","og_site_name":"Patagonia Ambiental","article_publisher":"https:\/\/www.facebook.com\/patagonia.ambiental","article_author":"https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","article_published_time":"2015-03-10T22:00:32+00:00","author":"Patagonia Ambiental","twitter_card":"summary_large_image","twitter_creator":"@PatAmb","twitter_site":"@PatAmb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/#article","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/"},"author":{"name":"Patagonia Ambiental","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d"},"headline":"Avanza la Comisi\u00f3n Nacional de Energ\u00eda At\u00f3mica \u00a0","datePublished":"2015-03-10T22:00:32+00:00","mainEntityOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/"},"wordCount":858,"publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/#primaryimage"},"thumbnailUrl":"","keywords":["CNEA","Kirchner","reindustrializaci\u00f3n"],"articleSection":["Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/","url":"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/","name":"Avanza la Comisi\u00f3n Nacional de Energ\u00eda At\u00f3mica \u00a0","isPartOf":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/#primaryimage"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-03-10T22:00:32+00:00","breadcrumb":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/patagoniambiental.com.ar\/info\/avanza-la-comision-nacional-de-energia-atomica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/patagoniambiental.com.ar\/info\/"},{"@type":"ListItem","position":2,"name":"Avanza la Comisi\u00f3n Nacional de Energ\u00eda At\u00f3mica \u00a0"}]},{"@type":"WebSite","@id":"https:\/\/patagoniambiental.com.ar\/info\/#website","url":"https:\/\/patagoniambiental.com.ar\/info\/","name":"Patagonia Ambiental","description":"Monitoreo y an\u00e1lisis de la situaci\u00f3n geopol\u00edtica en el mundo y su implicancia en la Patagonia","publisher":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/patagoniambiental.com.ar\/info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/patagoniambiental.com.ar\/info\/#organization","name":"Patagonia Ambiental","url":"https:\/\/patagoniambiental.com.ar\/info\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/","url":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","contentUrl":"https:\/\/patagoniambiental.com.ar\/info\/wp-content\/uploads\/2025\/05\/LOGO-PATAGONIA-AMBIENTAL.png","width":433,"height":250,"caption":"Patagonia Ambiental"},"image":{"@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/patagonia.ambiental","https:\/\/x.com\/PatAmb"]},{"@type":"Person","@id":"https:\/\/patagoniambiental.com.ar\/info\/#\/schema\/person\/db12bff64bbcbf6a253710bf0ea37b5d","name":"Patagonia Ambiental","description":"Andr\u00e9s Nievas T\u00e9cnico en manejo ambiental, consultor Ambiental y escritor para medios locales e internacionales sobre temas de geopolitica y medio ambiente.","sameAs":["http:\/\/www.patagoniambiental.com.ar","https:\/\/www.facebook.com\/share\/1C1V8Gv9BX\/?mibextid=qi2Omg","@patagoniambiental","https:\/\/youtube.com\/@patagoniaambiental2023?si=BLt58t0wuXquxlYZ"]}]}},"_links":{"self":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/9167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/comments?post=9167"}],"version-history":[{"count":0,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/posts\/9167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/media?parent=9167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/categories?post=9167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patagoniambiental.com.ar\/info\/wp-json\/wp\/v2\/tags?post=9167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}